{"id":16980,"date":"2021-12-15T22:34:33","date_gmt":"2021-12-15T21:34:33","guid":{"rendered":"https:\/\/www.monicamontella.it\/wordpress\/?p=16980"},"modified":"2022-02-16T15:24:41","modified_gmt":"2022-02-16T14:24:41","slug":"giustizia-e-pnrr","status":"publish","type":"post","link":"https:\/\/www.monicamontella.it\/wordpress\/2021\/12\/15\/giustizia-e-pnrr\/","title":{"rendered":"GIUSTIZIA e PNRR"},"content":{"rendered":"\n<p>\u00a0<\/p>\n<ol>\n<li><strong>Leggi prima <a href=\"https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/prima-Interrogazione-riforma-giustizia-e-PNRR-uff.pdf\"><span style=\"color: #ff0000;\">interrogazione<\/span><\/a><\/strong><\/li>\n<li><strong>Leggi seconda <a href=\"https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/seconda-Interrogazione-riforma-giustizia-e-PNRR-uff.pdf\"><span style=\"color: #ff0000;\">interrogazione<\/span><\/a><\/strong><\/li>\n<li><strong>Leggi terza <a href=\"https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/terza-Interrogazione-riforma-giustizia-e-PNRR-uff.pdf\"><span style=\"color: #ff0000;\">interrogazione<\/span><\/a><\/strong><\/li>\n<li><strong>Leggi la <span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/risoluzione-n-2-relazione-Cartabia-su-Giustizia.pdf\">risoluzione respinta<\/a> <\/span><\/strong><\/li>\n<\/ol>\n<p><strong>Leggi la <a href=\"https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/PNRR-e-GIUSTIZIA-tre-interrogazioni.pdf\"><span style=\"color: #ff0000;\">relazione<\/span><\/a> su GIUSTIZIA e PNRR<a href=\"https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/LOGO-IDV.png\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-17547 alignright\" src=\"https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/LOGO-IDV.png\" alt=\"\" width=\"149\" height=\"135\" \/><\/a><\/strong><\/p>\n<p>\u00a0\u201cL<em>a giustizia \u00e8 amministrata in nome del popolo. I giudici sono soggetti soltanto alla legge<\/em>\u201d (art.101), e \u201c<em>la funzione giurisdizionale \u00e8 esercitata da magistrati ordinari istituiti e regolati dalle norme sull\u2019ordinamento giudiziario<\/em>\u201d (art.102) \u201c<em>le norme sull\u2019ordinamento giudiziario e su ogni magistratura sono stabilite con legge. <strong>La legge assicura l\u2019indipendenza dei giudici<\/strong> delle giurisdizioni speciali, del pubblico ministero presso di esse, e degli estranei che partecipano all\u2019amministrazione della giustizia<\/em>\u201d (art. 108). Infine \u201c<em>le competenze del Consiglio superiore della magistratura, &#8230;. spettano al Ministro della giustizia<\/em><strong><em> l\u2019organizzazione e il funzionamento<\/em><\/strong><em> dei servizi relativi alla giustizia<\/em>\u201d (art. 110).<\/p>\n<p>Quindi gli attori principali che decidono, secondo la <span style=\"color: #ff0000;\"><strong><a style=\"color: #ff0000;\" href=\"https:\/\/www.senato.it\/sites\/default\/files\/media-documents\/Costituzione_novembre_2021.pdf\">Costituzione<\/a> <\/strong><\/span>italiana, della quantit\u00e0, qualit\u00e0 ed efficienza del sistema giudiziario in Italia sono il ministro della giustizia, i magistrati e il parlamento, quest&#8217;ultimo ha un ruolo fondamentale perch\u00e9 stabilisce <em>le norme sull\u2019ordinamento giudiziario e, soprattutto aspetto non trascurabile, <strong><span style=\"color: #ff0000;\"><a style=\"color: #ff0000;\" href=\"https:\/\/www.google.com\/url?sa=t&amp;rct=j&amp;q=&amp;esrc=s&amp;source=web&amp;cd=&amp;cad=rja&amp;uact=8&amp;ved=2ahUKEwiP26uJptb0AhVW8LsIHd5jDSAQwqsBegQIDBAB&amp;url=https%3A%2F%2Fwww.youtube.com%2Fwatch%3Fv%3DEm9w9K9zSmI&amp;usg=AOvVaw30XdyA8X5pZkKJbClHa0-C\">anche a seguito delle recenti dichiarazioni del magistrato Palamara<\/a><\/span><\/strong>,<strong> assicura l\u2019indipendenza dei giudici.<\/strong><\/em><!--more--><\/p>\n<p>Tra gli obiettivi dell\u2019<span style=\"color: #ff0000;\"><strong><a style=\"color: #ff0000;\" href=\"https:\/\/unric.org\/it\/agenda-2030\/\" target=\"_blank\" rel=\"noopener\">Agenda 2030<\/a><\/strong><\/span> &#8220;<em>per uno sviluppo sostenibile per contribuire allo sviluppo globale, promuovere il benessere umano e proteggere l\u2019ambiente<\/em>&#8221; \u00e8 previsto l&#8217;obiettivo numero <strong>16 <span class=\"Y2IQFc\" lang=\"it\">pace, <\/span><span class=\"Y2IQFc\" lang=\"it\">giustizia e istituzione stabile<\/span> (GOALS 16<\/strong> &#8211; peace justice and strong institution) <span class=\"Y2IQFc\" lang=\"it\">. <\/span><\/p>\n<h6><em><span id=\"page46R_mcid4\" class=\"markedContent\"><span dir=\"ltr\" role=\"presentation\"><span id=\"page83R_mcid11\" class=\"markedContent\">Obiettivo 16. Promuovere societ\u00e0 pacifiche e inclusive per uno sviluppo sostenibile, garantire a tutti l\u2019accesso alla <span class=\"highlight selected appended\">giustizia<\/span>, e creare istituzioni efficaci, responsabili ed inclusive a tutti i livelli. <\/span>La<\/span> <span dir=\"ltr\" role=\"presentation\">nuova<\/span> <span dir=\"ltr\" role=\"presentation\">Agenda<\/span> <span dir=\"ltr\" role=\"presentation\">riconosce<\/span> <span dir=\"ltr\" role=\"presentation\">il<\/span> <span dir=\"ltr\" role=\"presentation\">bisogno<\/span> <span dir=\"ltr\" role=\"presentation\">di<\/span> <span dir=\"ltr\" role=\"presentation\">costruire<\/span> <span dir=\"ltr\" role=\"presentation\">societ\u00e0<\/span> <span dir=\"ltr\" role=\"presentation\">pacifiche,<\/span> <span dir=\"ltr\" role=\"presentation\">giuste<\/span> <span dir=\"ltr\" role=\"presentation\">ed<\/span> <span dir=\"ltr\" role=\"presentation\">inclusive,<\/span> <span dir=\"ltr\" role=\"presentation\">che<\/span> <span dir=\"ltr\" role=\"presentation\">forniscano<\/span> <span dir=\"ltr\" role=\"presentation\">un<\/span> <span dir=\"ltr\" role=\"presentation\">accesso<\/span> <span dir=\"ltr\" role=\"presentation\">equo<\/span> <span dir=\"ltr\" role=\"presentation\">alla<\/span> <span dir=\"ltr\" role=\"presentation\"><span class=\"highlight selected appended\">giustizia<\/span><\/span> <span dir=\"ltr\" role=\"presentation\">e<\/span> <span dir=\"ltr\" role=\"presentation\">che<\/span> <span dir=\"ltr\" role=\"presentation\">si<\/span> <span dir=\"ltr\" role=\"presentation\">basino<\/span> <span dir=\"ltr\" role=\"presentation\">sul<\/span> <span dir=\"ltr\" role=\"presentation\">rispetto<\/span> <span dir=\"ltr\" role=\"presentation\">dei<\/span> <span dir=\"ltr\" role=\"presentation\">diritti<\/span> <span dir=\"ltr\" role=\"presentation\">umani<\/span> <span dir=\"ltr\" role=\"presentation\">(incluso<\/span> <span dir=\"ltr\" role=\"presentation\">il<\/span> <span dir=\"ltr\" role=\"presentation\">diritto<\/span> <span dir=\"ltr\" role=\"presentation\">allo<\/span> <span dir=\"ltr\" role=\"presentation\">sviluppo),<\/span> <span dir=\"ltr\" role=\"presentation\">sullo<\/span> <span dir=\"ltr\" role=\"presentation\">stato<\/span> <span dir=\"ltr\" role=\"presentation\">di<\/span> <span dir=\"ltr\" role=\"presentation\">diritto,<\/span> <span dir=\"ltr\" role=\"presentation\">sul<\/span> <span dir=\"ltr\" role=\"presentation\">buon<\/span> <span dir=\"ltr\" role=\"presentation\">governo<\/span> <span dir=\"ltr\" role=\"presentation\">a<\/span> <span dir=\"ltr\" role=\"presentation\">tutti<\/span> <span dir=\"ltr\" role=\"presentation\">i<\/span> <span dir=\"ltr\" role=\"presentation\">livelli<\/span> <span dir=\"ltr\" role=\"presentation\">e<\/span> <span dir=\"ltr\" role=\"presentation\">su<\/span> <span dir=\"ltr\" role=\"presentation\">istituzioni<\/span> <span dir=\"ltr\" role=\"presentation\">responsabili,<\/span> <span dir=\"ltr\" role=\"presentation\">effettive<\/span> <span dir=\"ltr\" role=\"presentation\">e<\/span> <span dir=\"ltr\" role=\"presentation\">trasparent<\/span><span dir=\"ltr\" role=\"presentation\">i.<\/span> <span dir=\"ltr\" role=\"presentation\">I<\/span> <span dir=\"ltr\" role=\"presentation\">fattori<\/span> <span dir=\"ltr\" role=\"presentation\">che<\/span> <span dir=\"ltr\" role=\"presentation\">danno<\/span> <span dir=\"ltr\" role=\"presentation\">luogo<\/span> <span dir=\"ltr\" role=\"presentation\">alla<\/span> <span dir=\"ltr\" role=\"presentation\">violenza,<\/span> <span dir=\"ltr\" role=\"presentation\">all\u2019insicurezza<\/span> <span dir=\"ltr\" role=\"presentation\">e <\/span><span dir=\"ltr\" role=\"presentation\">all\u2019ingiustizia,<\/span> <span dir=\"ltr\" role=\"presentation\">come<\/span> <span dir=\"ltr\" role=\"presentation\">la<\/span> <span dir=\"ltr\" role=\"presentation\">disuguaglianza,<\/span> <span dir=\"ltr\" role=\"presentation\">la<\/span> <span dir=\"ltr\" role=\"presentation\">corruzione,<\/span> <span dir=\"ltr\" role=\"presentation\">i<\/span> <span dir=\"ltr\" role=\"presentation\">governi<\/span> <span dir=\"ltr\" role=\"presentation\">inefficienti<\/span> <span dir=\"ltr\" role=\"presentation\">e<\/span> <span dir=\"ltr\" role=\"presentation\">flussi<\/span> <span dir=\"ltr\" role=\"presentation\">illeciti<\/span> <span dir=\"ltr\" role=\"presentation\">di<\/span> <span dir=\"ltr\" role=\"presentation\">armi<\/span> <span dir=\"ltr\" role=\"presentation\">e<\/span> <span dir=\"ltr\" role=\"presentation\">denaro<\/span> <span dir=\"ltr\" role=\"presentation\">sono<\/span> <span dir=\"ltr\" role=\"presentation\">tutti<\/span> <span dir=\"ltr\" role=\"presentation\">affrontati<\/span> <span dir=\"ltr\" role=\"presentation\">nell\u2019Agenda.<\/span> <br \/><br \/><span id=\"page83R_mcid14\" class=\"markedContent\"><span dir=\"ltr\" role=\"presentation\">16.3 <\/span> <span dir=\"ltr\" role=\"presentation\">Promuovere lo stato di diritto a livello nazionale <\/span><span dir=\"ltr\" role=\"presentation\">e internazionale e garantire un pari <\/span><span dir=\"ltr\" role=\"presentation\">accesso alla giustizia per tutti<\/span><\/span><\/span><\/em><\/h6>\n<p>Nel diritto fondamentale europeo \u00e8 garantito che &#8220;<em>Ogni persona ha diritto a che la sua causa sia esaminata equamente, pubblicamente ed entro un termine ragionevole da un giudice indipendente e imparziale, precostituito; ogni persona ha la facolt\u00e0 di farsi consigliare, difendere e rappresentare<\/em>&#8220;.<\/p>\n<p>Per capire il funzionamento, l&#8217;efficacia ed efficienza del sistema giudiziario italiano bisogna partire dall&#8217;analisi dei pochi dati\u00a0 &#8220;disponibili&#8221;.\u00a0<\/p>\n<p>Si parte dall&#8217;analisi del bilancio dello stato (rendiconto 2020) dove \u00e8 stato possibile elaborare i dati di <strong><span style=\"color: #ff0000;\"><a style=\"color: #ff0000;\" href=\"https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/rendiconto-2020-giustizia-6.png\">spesa stanziata, impegnata e pagata dal settore della giustizia<\/a><\/span><\/strong> per titolo (<strong>Tavola 1<\/strong>) e categorie economiche (<strong>Tavola 2<\/strong>). Dal lato delle spese per titolo, lo stanziamento iniziale, destinato al sistema giudiziario \u00e8 di quasi <span style=\"color: #ff0000;\"><strong>9 miliardi all\u2019anno<\/strong><\/span>, quello definitivo\u00a0 supera tale cifra ma di questo importo \u00e8 stato impegnato quasi un miliardo in meno, ed \u00e8 stato pagato il 95% dell\u2019impegnato (<span style=\"color: #ff0000;\"><strong>7,8 miliardi di euro<\/strong><\/span>).<\/p>\n<p>Soltanto il 36,8% della <a href=\"https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/rendiconto-2020-giustizia-7.png\"><strong><span style=\"color: #ff0000;\">spesa giudiziaria destinata agli investimenti<\/span><\/strong><\/a> \u00e8 stata impegnata, una <span style=\"color: #ff0000;\"><strong><a style=\"color: #ff0000;\" href=\"https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/rendiconto-2020-giustizia-8.png\">percentuale troppo bassa<\/a><\/strong><\/span> (soltanto il 4% della spesa \u00e8 stato impegnato per l&#8217;acquisto l&#8217;istallazione e l&#8217;ampliamento di immobili strutture ed impianti per l&#8217;amministrazione penitenziaria) considerando che questa spesa rappresenta appena il <strong>6,7%<\/strong> della spesa complessiva del ministero, in pratica poche risorse finanziarie destinate agli investimenti e neanche spese tutte.<\/p>\n<p><strong>Tavola 1<\/strong> &#8211; Rendiconto di gestione, spesa della giustizia per titolo, valori in euro, anno 2020<a href=\"https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/rendiconto-2020-giustizia-1.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-17162\" src=\"https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/rendiconto-2020-giustizia-1.png\" alt=\"\" width=\"928\" height=\"122\" srcset=\"https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/rendiconto-2020-giustizia-1.png 928w, https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/rendiconto-2020-giustizia-1-300x39.png 300w, https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/rendiconto-2020-giustizia-1-768x101.png 768w, https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/rendiconto-2020-giustizia-1-624x82.png 624w\" sizes=\"auto, (max-width: 928px) 100vw, 928px\" \/><\/a><em>Fonte:<\/em> <span style=\"color: #ff0000;\"><strong><a style=\"color: #ff0000;\" href=\"https:\/\/openbdap.mef.gov.it\/\">Open Bdap<\/a><\/strong><\/span><\/p>\n<p>Il personale (magistrati e figure amministrative) rappresenta il principale fattore produttivo nel settore giudiziario ed i costi pesano per il 70% sulla spesa totale che insieme al 20% dei <strong><span style=\"color: #ff0000;\"><a style=\"color: #ff0000;\" href=\"https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/rendiconto-2020-giustizia-5.png\">consumi intermedi<\/a><\/span><\/strong> (di cui l&#8217;80% \u00e8 impegnato dai tribunali) rappresentano <span style=\"text-decoration: underline;\">il <strong>90%<\/strong> della spesa pubblica destinata al sistema giudiziario italiano<\/span>.<\/p>\n<p><strong>Tavola 2<\/strong> &#8211; Rendiconto di gestione, spesa della giustizia per categoria economica, valori in euro, anno 2020<a href=\"https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/rendiconto-2020-giustizia-4.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-17217\" src=\"https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/rendiconto-2020-giustizia-4.png\" alt=\"\" width=\"992\" height=\"498\" srcset=\"https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/rendiconto-2020-giustizia-4.png 992w, https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/rendiconto-2020-giustizia-4-300x151.png 300w, https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/rendiconto-2020-giustizia-4-768x386.png 768w, https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/rendiconto-2020-giustizia-4-624x313.png 624w\" sizes=\"auto, (max-width: 992px) 100vw, 992px\" \/><\/a><em>Fonte:<\/em> <strong>MEF <a href=\"https:\/\/openbdap.mef.gov.it\/\"><span style=\"color: #ff0000;\">Open Bdap<\/span><\/a><\/strong><\/p>\n<p><em>\u201cAd ottobre 2020 nella <span style=\"color: #ff0000;\"><strong><a style=\"color: #ff0000;\" href=\"https:\/\/www.giustizia.it\/cmsresources\/cms\/documents\/rideterminazione_pianteorganiche_flessibili_relazione_tecnica_28ott2020.pdf\">relazione del ministero<\/a><\/strong><\/span> si apprende che si \u00e8 ampliata di fatto la dotazione organica&#8230;.del personale di magistratura di legittimit\u00e0 e &#8230;&#8230; di tutti gli uffici requirenti e giudicanti di merito \u201d.<\/em>\u00a0<\/p>\n<p>Nel <a href=\"https:\/\/www.giustizia.it\/giustizia\/it\/contentview.page?contentId=ART353232&amp;previsiousPage=mg_1_29_4_5_2\"><strong><span style=\"color: #ff0000;\">Conto annuale del personale<\/span> <\/strong><\/a>del ministero della giustizia i Magistrati in servizio al <strong>31 dicembre 2020<\/strong> risultano circa <strong>9.600 unit\u00e0<\/strong> di cui <strong><a href=\"https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/giustizia-magistrati-corte-di-appello.png\"><span style=\"color: #ff0000;\">1.860<\/span><\/a><\/strong><span style=\"color: #ff0000;\">\u00a0<\/span> sono addetti alle corti di appello e alle procure generali.<\/p>\n<p>Come noto, con <strong><span style=\"color: #ff0000;\"><a style=\"color: #ff0000;\" href=\"https:\/\/www.gazzettaufficiale.it\/eli\/id\/2018\/12\/31\/18G00172\/sg\">l\u2019articolo 1 comma 379 della legge 30 dicembre 2018, n. 145<\/a><\/span><\/strong> (bilancio di previsione dello Stato per l\u2019anno finanziario 2019 e bilancio pluriennale per il triennio 2019-2021) \u00e8 stata incrementata la pianta organica del personale della magistratura ordinaria di <strong>600 unit\u00e0<\/strong>, il numero dei posti della magistratura \u00e8 salito a <strong>10.751 unit\u00e0<\/strong>, grazie anche alla legge 25 ottobre 2016, n. 197, che ne ha permesso l\u2019ampliamento, mancano quindi all\u2019appello <strong>1.051 magistrati,<\/strong> il costo medio \u00e8 di <strong><a href=\"https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/stipendio-magistrati.png\"><span style=\"color: #ff0000;\">134 mila euro a testa<\/span><\/a><\/strong>.<\/p>\n<p>Rispetto alle 9.600 unit\u00e0 bisogna considerare che ci sono <strong>199 magistrati<\/strong> collocati fuori ruolo per incarichi amministrativi (ne sono <strong><span style=\"color: #ff0000;\"><a style=\"color: #ff0000;\" href=\"https:\/\/www.csm.it\/documents\/21768\/258978\/elenco+dei+magistrati+collocati+fuori+ruolo+presso+altri+uffici+o+enti+aggiornato+al+24+marzo+2017\/384c89f9-2e9e-bbba-485a-43fee94eac36\">161 nel 2021 i magistrati fuori ruolo,<\/a> <\/span><span style=\"color: #ff0000;\"><a style=\"color: #ff0000;\" href=\"https:\/\/www.csm.it\/documents\/21768\/258978\/elenco+dei+magistrati+collocati+fuori+ruolo+presso+organi+costituzionali+o+di+rilievo+costituzionale+aggiornato+al+24+marzo+2017\/2cef7657-353b-89ab-55b0-b9917476ebb6\">19 magistrati sono collocati presso il CSM sempre fuori ruolo<\/a><\/span><\/strong>\u00a0 e <strong><span style=\"color: #ff0000;\"><a style=\"color: #ff0000;\" href=\"https:\/\/www.csm.it\/documents\/21768\/258978\/elenco+dei+magistrati+collocati+fuori+ruolo+per+incarichi+elettivi+aggiornato+al+24+marzo+2017\/4bc500e3-82e2-3a8f-8ee8-bceab489b028\">19 Magistrati<\/a><\/span><\/strong> sono collocati fuori ruolo per incarichi elettivi).<\/p>\n<p>Il ministro Bonafede sul problema della carenza di organico nei tribunali italiani ha dichiarato che: \u201c<em>Ci sono <\/em><strong><em>360 magistrati che provengono da concorsi<\/em><\/strong><em> e che andranno a lavorare nei tribunali, oltre a 320 che arriveranno da concorsi pendenti&#8221;. <\/em>Il 15 dicembre 2021 \u00e8 stato bandito il concorso per <strong><span style=\"color: #ff0000;\"><a style=\"color: #ff0000;\" href=\"https:\/\/www.diritto.it\/concorso-magistratura-2022-tre-scritti-brevi-per-500-posti\/\">500 posti per magistrati<\/a><\/span><\/strong>.<\/p>\n<p>Secondo <span style=\"color: #ff0000;\">l&#8217;<a style=\"color: #ff0000;\" href=\"https:\/\/www.associazionemagistrati.it\/\"><strong><span style=\"color: #ff0000;\">associazione nazionale magistrati<\/span><\/strong><\/a><\/span> sarebbe stato necessario in primo luogo rivedere l'&#8221;anacronistica geografia&#8221; giudiziaria tra gli interventi pi\u00f9 urgenti per incidere sulle inefficienze del sistema giustizia. Il numero di 20 magistrati (tra Procura e Tribunale) \u00e8 quello minimo necessario per assicurare il buon funzionamento di un ufficio giudiziario, sottolineano i magistrati.<\/p>\n<p><strong>In Italia ben 59 Tribunali hanno un\u00a0organico inferiore alle 20 unit\u00e0.<\/strong> Tra essi ve ne sono addirittura due che coincidono con capoluoghi\u00a0di Corte d&#8217;Appello (L&#8217;Aquila e Campobasso), 15 Tribunali hanno un organico inferiore\u00a0alle 10 unit\u00e0. Il risultato cui\u00a0tendere come ha sottolineato recentemente il <strong>procuratore Gratteri<\/strong> \u00e8 la razionalizzazione della<span style=\"color: #ff0000;\"><strong><a style=\"color: #ff0000;\" href=\"https:\/\/temi.camera.it\/leg17\/post\/la_geografia_giudiziaria.html?tema=temi\/status_dei_magistrati\"> geografia\u00a0degli uffici giudiziari<\/a> <\/strong><\/span>(leggi il <strong><span style=\"color: #ff0000;\"><a style=\"color: #ff0000;\" href=\"https:\/\/giustizia.usb.it\/fileadmin\/archivio\/giustizia\/volantini_documenti\/Testo_integrale_commissione_Vietti_sul_riordino_della_geografia_giudiziaria.pdf\">testo<\/a><\/span> della commissione Vietti)<\/strong> intervenendo su quelli la cui sopravvivenza non appare giustificabile sotto il profilo dell&#8217;efficienza. Per ogni riforma della geografia giudiziaria, bisogna tener conto del <strong>rapporto tra abitanti e domanda di giustizia.<\/strong><\/p>\n<p>L&#8217;associazione nazionale magistrati ha proposto invece di unificare gli uffici di minime dimensioni con altri che hanno consistenza numerica superiore alle 10 unit\u00e0 (salve le peculiarit\u00e0 del territorio su cui operano); e di effettuare ulteriori accorpamenti per arrivare a regime alla dimensione ottimale di 20 magistrati (tra Procura e Tribunale).<\/p>\n<p><strong>\u201cSempre dalla <em><a href=\"https:\/\/www.giustizia.it\/cmsresources\/cms\/documents\/rideterminazione_pianteorganiche_flessibili_relazione_tecnica_28ott2020.pdf\"><span style=\"color: #ff0000;\">relazione del ministero<\/span><\/a><\/em> si apprende che era previsto gi\u00e0 dal 2020 un piano straordinario di assunzioni di personale amministrativo nella giustizia per circa 12.000 unit\u00e0 \u2026.&#8221;<\/strong><\/p>\n<p>Se si avessero avuto i dati a livello territoriale in termini sia di distribuzione sia di organizzazione interna del personale delle strutture giudiziarie sarebbe stato possibile e importante analizzare anche le maggiori disomogeneit\u00e0 della giustizia per area geografica.<\/p>\n<p>Un ulteriore fattore produttivo nella giustizia \u00e8 il sistema informatico giudiziario, <strong>ad esempio la digitalizzazione<\/strong> del processo, <strong>il potenziamento delle infrastrutture digitali con la revisione e diffusione dei sistemi telematici di gestione delle attivit\u00e0 processuali e di trasmissione di atti e provvedimenti<\/strong>.<\/p>\n<p>Il ministero della giustizia ha registrato una capacit\u00e0 di spesa dell\u2019<strong>88%<\/strong> (<strong>Tavola 2<\/strong>), lasciando per cos\u00ec dire nel \u201ccassetto\u201d una fetta consistente di risorse finanziarie che potevano essere utilizzate\u00a0 per la componente in conto capitale per pi\u00f9 di un miliardo di euro. In particolare la spesa impegnata dal dipartimento dell\u2019organizzazione giudiziaria per lo \u201c<a href=\"https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/rendiconto-2020-giustizia-3.png\"><em><strong><span style=\"color: #ff0000;\">sviluppo degli strumenti di innovazione tecnologica in materia informatica e telematica per l&#8217;erogazione dei servizi di giustizia<\/span><\/strong><\/em><\/a>\u201d \u00e8 stata di appena il 41% rispetto al suo stanziamento definitivo (ne aveva da spendere <strong>291 milioni di euro<\/strong>), altri 76 milioni non sono stati impegnati per la manutenzione straordinaria degli immobili del ministero ed altri 34 milioni non sono stati utilizzati per la manutenzione delle strutture giudiziarie ubicate nelle regioni della Campania, Puglia, Calabria e Sicilia.<\/p>\n<p><strong>Tavola 3<\/strong> &#8211; Rendiconto di gestione, spesa in conto capitale della giustizia per descrizione azione (aggregati di bilancio sottostanti i programmi di spesa), valori in euro, anno 2020<a href=\"https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/rendiconto-2020-giustizia-2.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-17167\" src=\"https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/rendiconto-2020-giustizia-2.png\" alt=\"\" width=\"992\" height=\"481\" srcset=\"https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/rendiconto-2020-giustizia-2.png 992w, https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/rendiconto-2020-giustizia-2-300x145.png 300w, https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/rendiconto-2020-giustizia-2-768x372.png 768w, https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/rendiconto-2020-giustizia-2-624x303.png 624w\" sizes=\"auto, (max-width: 992px) 100vw, 992px\" \/><\/a><em>Fonte:<\/em> MEF <strong><a href=\"https:\/\/openbdap.mef.gov.it\/\"><span style=\"color: #ff0000;\">Open Bdap<\/span><\/a><\/strong><\/p>\n<p>In definitiva il primo punto da porre al tavolo governativo a guida del Presidente Draghi per l\u2019attuazione del PNRR \u00e8 l\u2019analisi della &#8220;incapacit\u00e0 di spesa&#8221; di un ministero, che \u00e8 una realt\u00e0 facilmente verificabile dai dati contabili, questo rappresenta un forte limite non trascurabile nell&#8217;attuazione del PNRR e delle ingenti risorse messe in campo e che in parte si rischia non verranno mai utilizzate, oltre alla capacit\u00e0 del sistema giudiziario di svolgere i procedimenti con un numero inferiore di magistrati rispetto al potenziale della pianta organica.<\/p>\n<p>Oltre al numero precario dei magistrati e all\u2019incapacit\u00e0 di spesa del sistema giudiziario dobbiamo aggiungere un ulteriore elemento di criticit\u00e0 che emerge nell<strong><span style=\"color: #ff0000;\"><a style=\"color: #ff0000;\" href=\"https:\/\/eur-lex.europa.eu\/legal-content\/EN\/TXT\/?qid=1634640118533&amp;uri=CELEX%3A52021DC0389\">\u2019ultima relazione della commissione europea CEPE<\/a><\/span><\/strong>\u00a0 dove il sistema organizzativo della giustizia italiana risulta essere molto lento rispetto ad altri Stati membri in termini di <strong>tempi processuali<\/strong>. La lentezza della giustizia italiana riguarda tutte le sue componenti, civile, penale e amministrativa.<\/p>\n<p>Una priorit\u00e0 del semestre europeo continua a costituire il miglioramento dell<span style=\"text-decoration: underline;\"><span style=\"color: #ff0000; text-decoration: underline;\"><strong>&#8216;efficienza, la qualit\u00e0 e l&#8217;indipendenza<\/strong><\/span><\/span> dei sistemi giudiziari nazionali. Nella <strong><a href=\"https:\/\/ec.europa.eu\/info\/sites\/default\/files\/swd_2021_it.pdf\"><span style=\"color: #ff0000;\">relazione 2021\u00a0<\/span><\/a><\/strong> al paese la commissione europea sottolinea &#8220;<em>le<\/em><span id=\"page94R_mcid2\" class=\"markedContent\"><em><span dir=\"ltr\" role=\"presentation\"> misure di sostegno agli investimenti nazionali a <\/span><span dir=\"ltr\" role=\"presentation\">favore <\/span><span dir=\"ltr\" role=\"presentation\">della <\/span><span dir=\"ltr\" role=\"presentation\">digitalizzazione <\/span><span dir=\"ltr\" role=\"presentation\">de<\/span><span dir=\"ltr\" role=\"presentation\">gli <\/span><span dir=\"ltr\" role=\"presentation\">uffici <\/span><span dir=\"ltr\" role=\"presentation\">giudiziari, <\/span><span dir=\"ltr\" role=\"presentation\">tra <\/span><span dir=\"ltr\" role=\"presentation\">cui <\/span><span dir=\"ltr\" role=\"presentation\">una <\/span><span dir=\"ltr\" role=\"presentation\">procedura <\/span><span dir=\"ltr\" role=\"presentation\">completamente <\/span><span dir=\"ltr\" role=\"presentation\">digitalizzata per i procedimenti tanto civili quanto penali, lo sviluppo di sistemi avanzati per la <\/span><span dir=\"ltr\" role=\"presentation\">raccolta digitale di informazioni e dati procedurali, nonch\u00e9 il rafforzamento dello sviluppo di <\/span><span dir=\"ltr\" role=\"presentation\">c<\/span><\/em><span dir=\"ltr\" role=\"presentation\"><em>apacit\u00e0 dell&#8217;amministrazione della giustizia<\/em>&#8220;. <\/span><\/span><\/p>\n<p><strong>PNRR<\/strong> &#8211; <strong>Piano Nazionale di Ripresa e Resilienza &#8211; e GIUSTIZIA<br \/><\/strong><\/p>\n<p>Per rispondere alle varie criticit\u00e0 del sistema giudiziario oggi la grande occasione in Italia <strong>viene dal Piano Nazionale di Ripresa e Resilienza (da ora in poi PNRR)<\/strong> che intende garantire &#8220;<strong>un pari accesso alla giustizia per tutti<\/strong>&#8221; e renderla pi\u00f9 veloce ed equa un programma ampio e complesso composto da <strong>6 missioni, 16 componenti e circa 250 misure<\/strong>.<\/p>\n<p>Tutti gli italiani ormai sono informati delle potenzialit\u00e0 e delle risorse finanziarie messe in campo per sostenere gli investimenti complessivi in Italia per <strong>222,1 miliardi di euro<\/strong> <span style=\"text-decoration: underline;\">da spendere in meno di 6 anni<\/span>, di cui una parte \u00e8 composta dal dispositivo <em>del <strong>\u201cRecovery Fund\u201d<\/strong><\/em>\u00a0 <em>pari ai <strong>191,5 miliardi, 68,9 a fondo perduto e 122,5 in prestiti,<\/strong><\/em> e un <em><strong>fondo complementare<\/strong><\/em> nazionale desunto dal bilancio pubblico italiano per <strong>30,5 miliardi<\/strong>, un fiume di denaro<em> che permetter\u00e0 l\u2019erogazione da parte della commissione europea delle risorse assegnate\u00a0 per l\u2019attuazione del piano che il Governo italiano ha concordato con l\u2019Unione Europea in 10 rate,<\/em> risorse comunque vincolate al soddisfacimento di:<\/p>\n<ul>\n<li><em>528 condizioni da realizzare fino al 2026 <br \/><\/em><\/li>\n<li><em>213 \u201ctraguardi\u201d (milestones), ossia condizioni di natura qualitativa, e <\/em><\/li>\n<li><em>315 \u201cobiettivi\u201d (targets), ossia condizioni di natura quantitativa.<\/em><\/li>\n<\/ul>\n<p>Sono presenti 5 sezioni, le <strong>Priorit\u00e0 trasversali<\/strong> che hanno un impatto positivo sui giovani, sulla parit\u00e0 di genere e sulla riduzione dei divari territoriali, ci sono le 6 \u201cMissioni\u201d legate agli interventi del PNRR, le \u201cRisorse\u201d necessarie per ogni Missione e la sezione \u201cRiforme\u201d che illustra i contenuti, gli obiettivi e le tempistiche delle <a href=\"https:\/\/italiadomani.gov.it\/it\/riforme.html\"><strong><span style=\"color: #ff0000;\">Riforme orizzontali<\/span><\/strong><\/a>, abilitanti e settoriali.<\/p>\n<p>Gli investimenti previsti sono rappresentati dagli oltre <strong>150 progetti<\/strong> pubblicati sul sito web <a href=\"https:\/\/italiadomani.gov.it\/it\/home.html\"><strong><span style=\"color: #ff0000;\">italiadomani.gov.it<\/span><\/strong><\/a><strong>\u00a0 <\/strong>(Italia Domani fa parte del Next Generation EU, un progetto di rilancio economico dedicato agli Stati Membri) che rappresenta il portale ufficiale della presidenza del consiglio dei ministri e del ministero dell\u2019economia dedicato proprio alla comunicazione delle azioni messe in campo e al monitoraggio dei progetti per effetto del PNRR.<\/p>\n<p>Le riforme trasversali e settoriali sono quelle previste a costo zero ma che hanno un impatto notevole nella pubblica amministrazione italiana, nella giustizia, nella competizione e norme di semplificazione.<\/p>\n<p>Tra questi obiettivi e traguardi una sfida particolarmente importante e molto difficile da perseguire per la difficolt\u00e0 della materia \u00e8 proprio quella della <strong>giustizia<\/strong> legata alla complessit\u00e0 del processo penale e civile e all\u2019iter di approvazione del Parlamento di due leggi delega con cui il Governo potr\u00e0 poi adottare i decreti legislativi e attuativi che definiranno il contenuto specifico delle due riforme.<\/p>\n<p>Il piano fornisce soluzioni con una serie di riforme sia del ramo civile che di quello penale e del diritto amministrativo mirate all\u2019eliminazione dei blocchi che rallentano la definizione dei procedimenti, con l\u2019istituzione di un <a href=\"https:\/\/www.giustizia.it\/giustizia\/it\/mg_2_9_2.page\"><strong><span style=\"color: #ff0000;\">Ufficio del Processo<\/span><\/strong><\/a> (<strong><span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/webstat.giustizia.it\/Analisi%20e%20ricerche\/Monitoraggio%20UPP%202020.pdf\">introdotto in via sperimentale dal d.l. n. 90 del 2014)<\/a><\/span><\/strong> per aiutare il giudice, con una digitalizzazione completa dell\u2019attivit\u00e0, e l\u2019assunzione di personale tecnico che dovrebbe contribuire a smaltire i casi arretrati. In pratica si cerca di agire sulla capacit\u00e0 di gestione e organizzazione all\u2019interno dei tribunali.<\/p>\n<p>L&#8217;<strong><span style=\"color: #ff0000;\">asse 2 della componente M1C1 del PNRR<\/span><\/strong> contempla <em>&#8220;misure volte a rendere il sistema giudiziario pi\u00f9 efficiente riducendo la durata dei procedimenti e avvicinando l&#8217;Italia alla media dell&#8217;UE&#8221;.<\/em> Questa componente intende rispondere alle raccomandazioni specifiche per paese indirizzate all&#8217;Italia nel 2019 e 2020 di ridurre la durata dei processi civili e <strong>migliorare l&#8217;efficacia della lotta contro la corruzione<\/strong> (raccomandazioni specifiche per paese 2019, punto 4, e 2020, punto 4).<\/p>\n<p><strong>PNRR &#8211; Obiettivo M1C1-37 &#8211; Riforme 1.4 e 1.5 del processo civile e penale<\/strong><\/p>\n<p>Il piano intende completare l&#8217;adozione di tutti i regolamenti e delle fonti di diritto derivato necessari per l&#8217;effettiva applicazione delle leggi attuative per le riforme della giustizia.<\/p>\n<p><strong>Se parliamo di riforme non possiamo trascurare l&#8217;ordinamento giuridico<\/strong> che \u00e8 l&#8217;insieme ordinato e coerente delle norme giuridiche presenti in uno Stato che regolano la vita di una comunit\u00e0 all&#8217;interno di un sistema giuridico.<\/p>\n<p>In Italia \u00e8 ancora in vigore il provvedimento <a href=\"https:\/\/www.normattiva.it\/uri-res\/N2Ls?urn:nir:stato:regio.decreto:1941-01-30;12\"><strong><span style=\"color: #ff0000;\">REGIO DECRETO 30 gennaio 1941, n. 12<\/span><\/strong><\/a><span style=\"color: #ff0000;\">,<\/span> dal 21\/04\/1941 firmato da MUSSOLINI. Ricordo al Presidente Draghi che prima di tutto andrebbe aggiornato il testo dell&#8217;\u00ab<strong>Ordinamento giudiziario<\/strong>\u00bb ancora vigente seppur aggiornato con numerosi interventi legislativi <span style=\"color: #ff0000;\">(<a style=\"color: #ff0000;\" href=\"https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/leggi-ordinamento.png\"><strong><span style=\"color: #ff0000;\">15 leggi approvate<\/span><\/strong><\/a>).<\/span> L&#8217;ultimo aggiornamento all&#8217;atto \u00e8 stato fatto il 25\/07\/2018. Ci sono ancora articoli dell&#8217;ordinamento a cui si fa riferimento <span style=\"color: #ff0000;\"><a style=\"color: #ff0000;\" href=\"https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/ordinamento-giuridico-1.png\"><strong><span style=\"color: #ff0000;\">al Re<\/span> <span style=\"color: #ff0000;\">Imperatore<\/span><\/strong><\/a><\/span>. La Corte di Cassazione secondo <a href=\"https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/ordinamento-giuridico-2.png\"><strong><span style=\"color: #ff0000;\">l&#8217;art. 65 del regio decreto<\/span><\/strong><\/a> ha giurisdizione su tutto il territorio del <strong>Regno e dell&#8217;Impero<\/strong>.<\/p>\n<p>Nel frattempo con il cronoprogramma del PNRR si prevede <strong>che entro la fine del 2021<\/strong> bisogna realizzare la <strong><span style=\"color: red;\">riforma del processo civile<\/span><\/strong> con l\u2019entrata in vigore della legislazione attuativa e deve essere istituita la gestione elettronica obbligatoria di tutti i documenti e il processo diventa interamente telematico nei procedimenti civili.<a href=\"https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/riforma-civile.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-17503\" src=\"https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/riforma-civile-1024x172.png\" alt=\"\" width=\"625\" height=\"105\" srcset=\"https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/riforma-civile-1024x172.png 1024w, https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/riforma-civile-300x50.png 300w, https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/riforma-civile-768x129.png 768w, https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/riforma-civile-624x105.png 624w, https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/riforma-civile.png 1315w\" sizes=\"auto, (max-width: 625px) 100vw, 625px\" \/><\/a>Sempre <strong>entro la fine del 2021<\/strong> dovrebbe essere introdotta la digitalizzazione dei procedimenti penali di primo grado (ad esclusione dell&#8217;udienza preliminare) e deve essere creata una banca dati gratuita, pienamente accessibile e consultabile delle decisioni civili, conformemente alla legislazione.<\/p>\n<p>I dati di maggiore drammaticit\u00e0 sono proprio quelli relativi ai procedimenti pendenti, il rapporto tra pendenze e procedimenti esauriti e sopravvenienze assume attualmente proporzioni disarmanti.<\/p>\n<p><strong>PNRR &#8211; La riforma e investimenti nella giustizia civile<\/strong><\/p>\n<p><strong>La riforma 1.4<\/strong> <strong>della giustizia civile<\/strong> contenuta nel PNRR si incentra principalmente sulla riduzione <u>del tempo<\/u> del giudizio civile, individuando un ampio ventaglio di interventi volti a ridurre il numero di casi presso gli uffici giudiziari <u>semplificando le procedure esistenti, abbattendo l&#8217;arretrato e incrementando la produttivit\u00e0 degli uffici<\/u> medesimi.<\/p>\n<p>Per contenere l&#8217;esplosione del contenzioso presso gli uffici giudiziari \u00e8 accentuato il ricorso agli strumenti alternativi per la risoluzione delle controversie, in primis l&#8217;arbitrato e la<span style=\"color: #0000ff;\"><strong><a style=\"color: #0000ff;\" href=\"https:\/\/webstat.giustizia.it\/SitePages\/StatisticheGiudiziarie\/civile\/Mediazione%20Civile.aspx\"> mediazione<\/a><\/strong><\/span>, ed \u00e8 in revisione l&#8217;attuale sistema di quantificazione e recuperabilit\u00e0 delle spese giudiziarie.<\/p>\n<p>La semplificazione \u00e8 perseguita, con riferimento al procedimento di appello, potenziando il filtro di ammissibilit\u00e0, aumentando i casi in cui \u00e8 competente a pronunciarsi un solo giudice, garantendo l&#8217;effettiva attuazione di tempi procedurali vincolanti.<\/p>\n<p>La maggiore produttivit\u00e0 dovr\u00e0 ottenersi <strong>con un sistema di monitoraggio e incentivi per il raggiungimento di prestazioni standard <\/strong>presso tutti gli uffici giudiziari, mentre invece <u>bisognerebbe partire dal definire una sorta di <strong>livello essenziale delle prestazioni della giustizia LEPG<\/strong> per garantire &#8220;un pari accesso alla giustizia per tutti&#8221;<\/u>.<\/p>\n<p>La riforma prevede anche l&#8217;abbattimento dell&#8217;arretrato negli uffici giudiziari, obiettivo raggiungibile grazie alle assunzioni temporanee previste, incluse nella componente investimento.<\/p>\n<p>Ricordo che la <strong><span style=\"color: #ff0000;\"><a style=\"color: #ff0000;\" href=\"https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/giustizia-istat-annuario-1.png\">giustizia civile<\/a><\/span><\/strong> si occupa principalmente di separazioni, divorzi, tutela, affidamento e adozioni dei minori, lavoro, previdenza e assistenza, <strong><span style=\"color: #ff0000;\"><a style=\"color: #ff0000;\" href=\"https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/giustizia-istat-annuario-3.png\">protesti<\/a><\/span><\/strong> e fallimenti, procedure concorsuali, esecuzioni mobiliari ed immobiliari. In pratica la giustizia civile tocca la vita privata dei cittadini, la famiglia, il lavoro, l\u2019impresa, quindi se non \u00e8 organizzata bene \u00e8 un disastro per l&#8217;intera societ\u00e0 italiana.\u00a0<\/p>\n<p>La riforma che contiene la \u201c<em>Delega al Governo per l\u2019efficienza del processo civile e per la revisione della disciplina degli strumenti di risoluzione alternativa delle controversie e misure urgenti di razionalizzazione dei procedimenti in materia di diritti delle persone e delle famiglie nonch\u00e9 in materia di esecuzione forzata<\/em>\u201c \u00e8 stata approvata gioved\u00ec 25 novembre 2021 con <strong>364 voti<\/strong> favorevoli, 32 contrari e 7 astenuti, dove tra le novit\u00e0 introdotte ci sono l\u2019<strong>istituzione del Tribunale per la famiglia ed i minori<\/strong>, maggiori tutele per le donne ed i minori che subiscono violenza, processi pi\u00f9 veloci grazie alla semplificazione dei procedimenti, sostegni fiscali per la <strong>risoluzione delle controversie (<\/strong>le ADR, Alternative dispute resolution, sono <strong>strumenti alternativi)<\/strong>.<\/p>\n<p>Il Ministero della Giustizia effettua da anni un <strong><span style=\"color: #ff0000;\"><a style=\"color: #ff0000;\" href=\"https:\/\/www.giustizia.it\/giustizia\/it\/mg_2_9_13.page\">monitoraggio<\/a><\/span><\/strong> da cui emerge, per quanto riguarda la giustizia civile, un enorme divario tra <strong>tribunali del Nord e quelli del Sud, un tribunale al sud potrebbe avere tempi di definizione pi\u00f9 lunghi perch\u00e9, a parit\u00e0 di carico di lavoro, dispone di meno risorse (umane e finanziarie) rispetto di altri uffici del nord. <\/strong><\/p>\n<p>\u201cL\u2019efficacia si definisce come il grado di raggiungimento di un obiettivo, l\u2019efficienza come la capacit\u00e0 di raggiungere quell\u2019obiettivo evitando lo spreco di risorse&#8221;.<\/p>\n<p>Analizziamo un po&#8217; di dati sulla giustizia civile!<\/p>\n<p>I procedimenti civili pendenti a fine anno in primo grado nel 2019 sono quasi <strong>3,4 milioni<\/strong> tra giudice di pace, tribunali e corte di appello.<\/p>\n<h4><em><strong>Grafico 1 &#8211; Procedimenti civili pendenti per grado di giudizio e ufficio giudiziario, anno 2019<\/strong><\/em><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-17322\" src=\"https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/giustizia-istat-annuario-4-1024x444.png\" alt=\"\" width=\"625\" height=\"271\" srcset=\"https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/giustizia-istat-annuario-4-1024x444.png 1024w, https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/giustizia-istat-annuario-4-300x130.png 300w, https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/giustizia-istat-annuario-4-768x333.png 768w, https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/giustizia-istat-annuario-4-1536x666.png 1536w, https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/giustizia-istat-annuario-4-2048x888.png 2048w, https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/giustizia-istat-annuario-4-624x271.png 624w\" sizes=\"auto, (max-width: 625px) 100vw, 625px\" \/><em>Fonte:<\/em> <a href=\"https:\/\/www.istat.it\/storage\/ASI\/2021\/capitoli\/C06.pdf\"><strong><span style=\"color: #ff0000;\">Annuario Istat<\/span><\/strong><\/a><\/h4>\n<p>Gli arretrati civili totali sono<strong> 530 mila nel 2020 tra cassazione<\/strong> (+ un anno), corte d\u2019appello (+ due anni) e tribunali (+3 anni).<\/p>\n<p>I procedimenti civili pendenti dinanzi a tutti gli uffici giudiziari italiani sono aumentati in cassazione di quasi <span style=\"color: #ff0000;\"><a style=\"color: #ff0000;\" href=\"https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/giustizia-ministero-annuario-1.png\"><strong><span style=\"color: #ff0000;\">20.000 pratiche<\/span><\/strong><\/a><\/span> mentre si sono dimezzati nei tribunali e in corte di appello (<strong><a href=\"https:\/\/webstat.giustizia.it\/SitePages\/Home.aspx\"><em><span style=\"color: #ff0000;\">fonte: ministero della giustizia<\/span><\/em><\/a>)<\/strong>.<\/p>\n<p>Solo per la <strong><span style=\"color: #ff0000;\"><a style=\"color: #ff0000;\" href=\"https:\/\/www.cortedicassazione.it\/cassazione-resources\/resources\/cms\/documents\/20210107_ANNUARIO-Civile2020.pdf\">Corte Suprema di Cassazione<\/a><\/span><\/strong> i procedimenti civili risultano 32 mila iscritti nel 2020, 29 mila procedimenti definiti con la pubblicazione del provvedimento o eliminati ma ne restano pendenti a fine anno ben<strong><a href=\"https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/giustizia-cassazione-1.png\"><span style=\"color: #ff0000;\"> 120 mila<\/span><\/a>,<\/strong> aumentata rispetto al 31 dicembre 2019 del 2,9% (<strong>+3.440 pendenti)<\/strong>; in pratica possiamo sostenere che ci sono in Italia 120 mila utenti che aspettano da 8 anni un giudizio definitivo in sede civile, di cui <strong>53 mila procedimenti<\/strong> sono nell&#8217;ambito del <strong><span style=\"color: #ff0000;\"><a style=\"color: #ff0000;\" href=\"https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/grafico-cassazione-civile.png\">settore tributario<\/a><\/span><\/strong>\u00a0 che rappresenta il <strong>44%<\/strong> del totale dei procedimenti pendenti (<em>fonte: Annuario Corte di Cassazione<\/em>).<\/p>\n<p>Con la riforma <strong>1.6 \u2013 Insolvenza<\/strong> si intende digitalizzare e potenziare il processo esecutivo con meccanismi di allerta precoce pre-insolvenza e la specializzazione di organi giudiziari e pre-giudiziari per una gestione pi\u00f9 efficiente di tutte le fasi del processo esecutivo, anche tramite la formazione e la specializzazione del personale giudiziario e amministrativo. Sono stati introdotti <strong>meccanismi di allerta sia a carico del collegio sindacale sia a carico di creditori qualificati<\/strong> in possesso di informazioni rilevanti in ordine alla situazione del debitore. \u00c8 stato introdotto il nuovo istituto della \u201c<strong>composizione negoziata della crisi<\/strong>\u201d alla quale potranno accedere, come riporta la <strong><a href=\"https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/12_PNRR_Giustizia.pdf\"><span style=\"color: #ff0000;\">relazione del Ministero<\/span><\/a><\/strong> su base esclusivamente volontaria, a far data dal 15 novembre 2021, tutti gli imprenditori iscritti nel <u>registro delle imprese<\/u> che si trovano in condizioni di squilibrio patrimoniale o economico-finanziario, che ne rendano probabile la crisi o l\u2019insolvenza. Si tratta di un percorso volontario ed extragiudiziale caratterizzato dalla riservatezza ed \u00e8 attivabile solo dalle imprese che decidono di farvi ricorso. Per incentivare l\u2019utilizzo di questo istituto, l\u2019accesso alla procedura \u00e8 accompagnato da una serie di benefici sul piano fiscale come la riduzione dell\u2019entit\u00e0 degli interessi sui debiti tributari e sulle sovrattasse, l\u2019ampliamento delle rateizzazioni, ecc. e non contempla, nel caso d\u2019insuccesso, il passaggio automatico a una procedura fallimentare n\u00e9 la segnalazione al Pubblico Ministero. Viene, inoltre, introdotta una nuova procedura concorsuale denominata \u00ab<strong>concordato semplificato per la liquidazione del patrimonio<\/strong>\u00bb, la cui proposta pu\u00f2 essere presentata dall\u2019imprenditore quando l\u2019esperto nella relazione finale dichiara che le trattative non hanno avuto esito positivo.<\/p>\n<p>Il Governo prevede di apportare modifiche al c.d. Codice della crisi d&#8217;impresa e dell&#8217;insolvenza:<\/p>\n<ul>\n<li>attuando la direttiva UE n. 1023\/2019, relativa alle procedure di risanamento, insolvenza ed <span style=\"color: #0000ff;\"><strong><a style=\"color: #0000ff;\" href=\"https:\/\/webstat.giustizia.it\/SitePages\/StatisticheGiudiziarie\/civile\/Monitoraggio%20OCC.aspx\">esdebitazione<\/a><\/strong>;<\/span><\/li>\n<li>rivedendo gli accordi di risoluzione extragiudiziale al fine di incentivare le parti a farne un maggior uso;<\/li>\n<li>potenziando i meccanismi di allerta;<\/li>\n<li>specializzando gli uffici giudiziari e le autorit\u00e0 amministrative competenti per le procedure concorsuali;<\/li>\n<li>implementando la digitalizzazione delle procedure anche attraverso la creazione di una apposita piattaforma online.<\/li>\n<\/ul>\n<p>Meriterebbe un approfondimento maggiore l&#8217;ambito organizzativo dei <strong><span style=\"color: #ff0000;\"><a style=\"color: #ff0000;\" href=\"https:\/\/def.finanze.it\/DocTribFrontend\/getPrassiDetail.do?id=%7BB752EE50-1E07-40B8-BF5B-09EA49FA2B4A%7D\">procedimenti tributari<\/a> <\/span><\/strong>ma resta il fatto che per l&#8217;obiettivo <strong>M1C1-35<\/strong> &#8211; <span style=\"color: #ff0000;\"><strong><a style=\"color: #ff0000;\" href=\"https:\/\/www.questionegiustizia.it\/rivista\/articolo\/la-riforma-della-giustizia-tributaria-e-l-unitarieta-della-giurisdizione_380.php\">Riforma 1.7 delle commissioni tributarie<\/a> <\/strong><\/span>di primo e secondo grado sarebbe interessante avere pi\u00f9 elementi informativi proprio per meglio contribuire all&#8217;efficacia della riforma prevista nel PNRR, traguardo previsto su disposizione nella normativa che indica l&#8217;entrata in vigore della riforma del quadro giuridico che deve avere l&#8217;obiettivo di rendere pi\u00f9 efficace (<strong>MA COME?<\/strong>) l&#8217;applicazione della legislazione tributaria e <u>ridurre l&#8217;elevato numero di ricorsi<\/u> alla Corte di Cassazione.<a href=\"https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/riforma-tributaria-.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-17508\" src=\"https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/riforma-tributaria--1024x564.png\" alt=\"\" width=\"625\" height=\"344\" srcset=\"https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/riforma-tributaria--1024x564.png 1024w, https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/riforma-tributaria--300x165.png 300w, https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/riforma-tributaria--768x423.png 768w, https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/riforma-tributaria--624x344.png 624w, https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/riforma-tributaria-.png 1315w\" sizes=\"auto, (max-width: 625px) 100vw, 625px\" \/><\/a>In che modo si vuole ridurre il numero dei ricorsi con le cancellazioni o prescrizioni o con accordi transattivi che mirano a far recuperare un p\u00f2 di risorse finanziarie al fisco?<\/p>\n<p>La <strong>riforma del codice di procedura civile<\/strong> contenuta nel PNRR, invece prevede l\u2019istituzione dell\u2019<strong>Ufficio del processo<\/strong>, che dovrebbe velocizzare la durata dei processi civili migliorando il funzionamento di tutta la giurisdizione. Si auspica una riduzione dei tempi da nove a cinque anni per la definizione delle <strong>procedure fallimentari<\/strong> (importante per il sistema produttivo italiano). Le istanze di fallimento presso i tribunali ordinari sono state pi\u00f9 di <strong>30 mila sopravvenute nel 2019<\/strong> ne restano pendenti a fine anno pi\u00f9 di 9.000. Le procedure fallimentari invece ne restano <strong>82.828 pendenti<\/strong> <strong>a fine anno<\/strong> (vedi <a href=\"https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/tavola-6.4-istat.png\"><strong><span style=\"color: #ff0000;\">Tavola 6.4<\/span><\/strong><\/a> Movimento dei procedimenti civili presso i Tribunali ordinari per materia,<strong><span style=\"color: #ff0000;\"><a style=\"color: #ff0000;\" href=\"https:\/\/www.istat.it\/storage\/ASI\/2021\/capitoli\/C06.pdf\"> Istat annuario<\/a><\/span><\/strong>).<\/p>\n<p><strong>PNRR &#8211; La riforma e gli investimenti previsti nella giustizia penale<\/strong><\/p>\n<p>Nel PNRR <strong>la riforma 1.5<\/strong> che riguarda la giustizia penale <strong>intende invece ridurre <u>il tempo del giudizio<\/u> penale,<\/strong> individuando un ampio ventaglio di interventi, <u>semplificando le procedure esistenti e incrementando la produttivit\u00e0 degli uffici giudiziari<\/u>. La semplificazione \u00e8 perseguita ampliando la possibilit\u00e0 di ricorso a procedure semplificate, diffondendo l&#8217;uso della tecnologia digitale, assicurando scansioni temporali stringenti dell&#8217;udienza preliminare, riesaminando il sistema delle notificazioni per renderlo pi\u00f9 efficace. La maggiore produttivit\u00e0 dovr\u00e0 ottenersi con un sistema di monitoraggio e incentivi per il raggiungimento di prestazioni standard presso tutti gli uffici giudiziari.<\/p>\n<p><a href=\"https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/riforma-penale.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-17505\" src=\"https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/riforma-penale-1024x213.png\" alt=\"\" width=\"625\" height=\"130\" srcset=\"https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/riforma-penale-1024x213.png 1024w, https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/riforma-penale-300x63.png 300w, https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/riforma-penale-768x160.png 768w, https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/riforma-penale-624x130.png 624w, https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/riforma-penale.png 1315w\" sizes=\"auto, (max-width: 625px) 100vw, 625px\" \/><\/a>La Giustizia penale si occupa dei delitti denunciati dalle Forze dell&#8217;Ordine \u2013 della criminalit\u00e0 \u2013 della criminalit\u00e0 minorile \u2013 dei suicidi e tentativi di suicidio.<\/p>\n<p>Analizziamo un po&#8217; di dati sulla giustizia penale!<\/p>\n<p>I procedimenti penali pendenti a fine anno sono pi\u00f9 di <strong>due milioni<\/strong> nel 2020 tra procure Gip e tribunali, nel primo grado di giudizio. I tribunali con rito monocratico hanno <strong>633 mila<\/strong> procedimenti pendenti a fine anno 2020. Altro dato allarmante \u00e8 il numero dei procedimenti penali delle corti di appello, sono <strong>269 mila<\/strong> in attesa di giudizio.<\/p>\n<p>Anche i pi\u00f9 piccoli della societ\u00e0 italiana soffrono della lentezza del sistema giudiziario sono <strong>36 mila i minori<\/strong> che pendono a fine anno un giudizio del <strong><span style=\"color: #ff0000;\">Giudice per le indagini preliminari<\/span><\/strong> (GIP) e <strong><span style=\"color: #ff0000;\">Giudice dell\u2019udienza preliminare<\/span><\/strong> (GUP) in un tribunale per i minorenni.<\/p>\n<p><strong>Tavola 4<\/strong> &#8211; Procedimenti penali per grado di giudizio e ufficio giudiziario, anno 2020<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-17332\" src=\"https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/giustizia-istat-annuario-5.png\" alt=\"\" width=\"788\" height=\"601\" srcset=\"https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/giustizia-istat-annuario-5.png 788w, https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/giustizia-istat-annuario-5-300x229.png 300w, https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/giustizia-istat-annuario-5-768x586.png 768w, https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/giustizia-istat-annuario-5-624x476.png 624w\" sizes=\"auto, (max-width: 788px) 100vw, 788px\" \/><\/p>\n<h4><em>Fonte:<\/em> <a href=\"https:\/\/www.istat.it\/storage\/ASI\/2021\/capitoli\/C06.pdf\"><strong><span style=\"color: #ff0000;\">Annuario Istat<\/span><\/strong><\/a><\/h4>\n<p>Solo presso la<span style=\"color: #ff0000;\"><strong><a style=\"color: #ff0000;\" href=\"https:\/\/www.cortedicassazione.it\/cassazione-resources\/resources\/cms\/documents\/ANNUARIO_PENALE_2020.pdf\"> Cassazione nel 2020<\/a><\/strong><\/span> su 38 mila procedimenti penali iscritti, 14 mila sono risultati definiti o eliminati mentre ben <span style=\"text-decoration: underline;\"><strong>24 mila sono rimasti pendenti a fine anno<\/strong><\/span>.<\/p>\n<p>Dal <a href=\"https:\/\/www.questionegiustizia.it\/articolo\/quanto-costa-la-giustizia-i-tribunali-italiani-tra-efficacia-ed-efficienza_17-02-2020.php\"><strong><span style=\"color: #ff0000;\">monitoraggio penale<\/span><\/strong><\/a> del Ministero della Giustizia (anno 2013) si stimava un numero di procedimenti definiti per giudice compreso tra 158 e 1.369. Lo stesso monitoraggio stimava che il numero di procedimenti definiti per giudice nel settore civile (su dati 2015) variasse da 322 a 1.250. Differenze analoghe riguardano anche il numero di nuove cause civili e penali per giudice, o il numero di abitanti per giudice.<\/p>\n<p>Con la <strong><span style=\"color: #ff0000;\"><a style=\"color: #ff0000;\" href=\"https:\/\/www.giurisprudenzapenale.com\/wp-content\/uploads\/2021\/10\/LEGGE-27-settembre-2021-n.-134.pdf\">legge<\/a><\/span><\/strong> <span id=\"articleText\">27 settembre 2021, n. 134 \u00e8 stata approvata in via definitiva una nuova <strong>riforma della giustizia penale<\/strong>, che mira a <strong>ridurre i tempi <\/strong>del processo penale con l\u2019introduzione del \u00ab<strong>processo penale telematico<\/strong> per la <strong>celerit\u00e0 <\/strong>e l\u2019<strong>efficienza <\/strong>del procedimento e sono state modificate la materia di prescrizione e la ragionevole durata dei giudizi di impugnazione. Per la <strong>transizione digitale della giustizia penale <\/strong>la <strong>documentazione dell\u2019interrogatorio o della prova dichiarativa<\/strong>, verr\u00e0 effettuata anche mediante registrazione audiovisiva, e la previsione di ipotesi di <strong>partecipazione a distanza <\/strong>ad atti o udienze.<\/span><\/p>\n<p>A questa lentezza del sistema giustizia si pone rimedio anche con un aumento consistente del personale amministrativo.<\/p>\n<p><strong>PNRR &#8211; Procedure di assunzione per i tribunali civili, penali e amministrativi <\/strong><\/p>\n<p>I Tribunali sono strutture ad alta intensit\u00e0 di lavoro, il diverso livello di efficienza quindi risiede nella ripartizione e nell\u2019organizzazione interna delle risorse umane utilizzate che incide sulla durata dei processi.<\/p>\n<p>Con <strong>l&#8217;investimento 1.8 Obiettivo M1C1-32 Investimento 1.8 &#8211; <\/strong>del PNRR\u00a0 si prevede un notevole investimento in capitale umano nel sistema giudiziario italiano. Attualmente il personale a tempo indeterminato amministrativo del Dipartimento per gli affari di giustizia e del Dipartimento dell&#8217;organizzazione giudiziaria <strong>aggiornato al 30 ottobre 2020 \u00e8 di <span style=\"color: #ff0000;\"><a style=\"color: #ff0000;\" href=\"https:\/\/www.giustizia.it\/giustizia\/it\/contentview.page?contentId=ART279428&amp;previsiousPage=mg_1_29_4_5\">43.462 unit\u00e0<\/a><\/span>.<\/strong><a href=\"https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/raccordo-1-PNRR-giustizia.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-17004\" src=\"https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/raccordo-1-PNRR-giustizia.png\" alt=\"\" width=\"951\" height=\"101\" srcset=\"https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/raccordo-1-PNRR-giustizia.png 951w, https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/raccordo-1-PNRR-giustizia-300x32.png 300w, https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/raccordo-1-PNRR-giustizia-768x82.png 768w, https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/raccordo-1-PNRR-giustizia-624x66.png 624w\" sizes=\"auto, (max-width: 951px) 100vw, 951px\" \/><\/a>Con il PNRR si interviene soltanto con l\u2019assunzione di personale dipendente a tempo determinato, infatti si intende agire a breve termine sui fattori organizzativi di modo che le riforme in fase di sviluppo producano risultati pi\u00f9 rapidamente, massimizzando le sinergie e realizzando un cambiamento epocale grazie alle risorse straordinarie previste dal piano.<\/p>\n<p>Nel piano non viene affrontato il tema di porre rimedio alla carenza del numero di magistrati per i tribunali e le corti. Inoltre senza giudici non si possono ridurre i tempi dei processi perch\u00e9 sono loro che devono determinare la sentenza. A meno che non si vuole raggiungere l\u2019obiettivo del piano con altri meccanismi come la \u201cgiustizia negata\u201d. Il Governo infatti nella <strong><span style=\"color: #ff0000;\"><a style=\"color: #ff0000;\" href=\"https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/12_PNRR_Giustizia.pdf\">relazione del Ministero<\/a><\/span><\/strong> ha citato che &#8220;<em>Nel perseguire l\u2019obiettivo di una riduzione dei tempi della giustizia penale e ridurre la pressione sul sistema giudiziario, la riforma estende infatti le possibilit\u00e0 di estinguere il reato, o comunque di <strong>renderlo improcedibile<\/strong>, in caso di condotte riparatorie e, in particolare, di risarcimento del danno<\/em>&#8230;.&#8221; &#8220;&#8230;I<em>ntrodurre rimedi giurisdizionali contro le eventuali stasi del procedimento e filtri che consentano di <span style=\"text-decoration: underline;\"><strong>selezionare i processi davvero meritevoli di essere portati all\u2019attenzione del giudice<\/strong><\/span><\/em>&#8220;.<\/p>\n<p><em>Con il PNRR &#8220;al fine di ridurre l&#8217;arretrato e i tempi di esaurimento dei procedimenti ci si affida allo strumento organizzativo, il cosiddetto &#8220;<\/em><strong><em>Ufficio del processo<\/em><\/strong><em>&#8220;, che consiste nell&#8217;istituire (o rafforzare se gi\u00e0 esistenti) risorse a supporto dei giudici <\/em><strong><em>(reclutate a tempo determinato)<\/em><\/strong><em>. Questa misura migliorerebbe inoltre la qualit\u00e0 dell&#8217;azione giudiziaria sostenendo i giudici nelle normali attivit\u00e0 di studio, ricerca, preparazione delle bozze di provvedimenti, organizzazione dei fascicoli, e consentendo loro di concentrarsi sui compiti pi\u00f9 complessi. L&#8217;investimento comprende anche la formazione a supporto della <u>transizione digitale del sistema giudiziario&#8221;.<\/u><\/em><\/p>\n<p>Le risorse finanziarie assegnate dal piano per le procedure di assunzione per i tribunali civili, penali sono<span style=\"color: #ff0000;\"><strong> 2,268 miliardi di euro <\/strong><\/span><span style=\"color: #ff0000;\"><span style=\"color: #000000;\">e<\/span><\/span> si pone l&#8217;obiettivo di finanziare un piano di assunzioni per aiutare i giudici nella gestione delle pratiche e digitalizzare i processi, per rendere la giustizia pi\u00f9 efficace ed efficiente. Un programma ampio per garantire l\u2019esecuzione dei progetti previsti in maniera veloce e rapida. Quindi ci si aspetta che il risultato dell\u2019investimento comporti:<\/p>\n<ul>\n<li>Processi civili e penali pi\u00f9 rapidi;<\/li>\n<li>Nuovi posti di lavoro per i giovani laureati in legge, economia e scienze politiche, ma anche per diplomati e personale specializzato;<\/li>\n<li>Una giustizia pi\u00f9 efficace.<\/li>\n<\/ul>\n<p>Il cronoprogramma prevede che entro <strong>dicembre del 2022<\/strong> si avviano le procedure di assunzione di almeno <strong>8.764 dipendenti<\/strong> con la conseguente entrata in servizio nell<strong>\u2019ufficio per il processo<\/strong> per i tribunali civili e penali, il valore di riferimento deve essere il numero dei dipendenti del personale alla fine del 2021.<a href=\"https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/raccordo-2-PNRR-giustizia.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-17006\" src=\"https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/raccordo-2-PNRR-giustizia-1024x135.png\" alt=\"\" width=\"625\" height=\"82\" srcset=\"https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/raccordo-2-PNRR-giustizia-1024x135.png 1024w, https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/raccordo-2-PNRR-giustizia-300x40.png 300w, https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/raccordo-2-PNRR-giustizia-768x102.png 768w, https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/raccordo-2-PNRR-giustizia-624x83.png 624w, https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/raccordo-2-PNRR-giustizia.png 1315w\" sizes=\"auto, (max-width: 625px) 100vw, 625px\" \/><\/a>Entro <strong>giugno 2024<\/strong> si dovranno concludere le procedure di assunzione per i tribunali civili e penali e completare le procedure di assunzione di almeno <strong>19.719 dipendenti<\/strong> nell<strong>\u2019ufficio per il processo<\/strong> per i tribunali civili e penali ed entrata in servizio di tali dipendenti. Il valore di riferimento deve essere il numero di dipendenti del personale alla fine del 2021.<a href=\"https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/raccordo-3-PNRR-giustizia.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-17011\" src=\"https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/raccordo-3-PNRR-giustizia-1024x129.png\" alt=\"\" width=\"625\" height=\"79\" srcset=\"https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/raccordo-3-PNRR-giustizia-1024x129.png 1024w, https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/raccordo-3-PNRR-giustizia-300x38.png 300w, https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/raccordo-3-PNRR-giustizia-768x97.png 768w, https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/raccordo-3-PNRR-giustizia-624x79.png 624w, https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/raccordo-3-PNRR-giustizia.png 1315w\" sizes=\"auto, (max-width: 625px) 100vw, 625px\" \/><\/a><strong>\u00a0<\/strong>Con l&#8217;investimento <strong>1.8 &#8211; <\/strong>si intende anche<strong> r<\/strong>afforzare l&#8217;Ufficio del processo per la Giustizia amministrativa (risorse finanziarie previste <span style=\"color: #ff0000;\"><strong>41,9 milioni di euro<\/strong><\/span>).<\/p>\n<p>La misura si pone l&#8217;obiettivo di finanziare un piano straordinario di assunzioni per rafforzare l\u2019Ufficio del processo. I nuovi assunti, adeguatamente formati, andranno a coprire le sedi degli Uffici giudiziari che hanno maggiori arretrati da smaltire e aiuteranno nelle attivit\u00e0 di monitoraggio e rendicontazione del PNRR.<\/p>\n<p>Risultato dell\u2019investimento previsto:<\/p>\n<ul>\n<li>Una giustizia pi\u00f9 efficace: riduzione della durata dei processi e smaltimento dei processi in ritardo;<\/li>\n<li>Nuovi posti di lavoro;<\/li>\n<li>Una giustizia pi\u00f9 digitale;<\/li>\n<li>Nuove competenze digitali.<\/li>\n<\/ul>\n<p>Entro <strong>dicembre 2021<\/strong> si prevede l&#8217;entrata in vigore della legislazione speciale da approvare per la disciplina delle assunzioni nell\u2019ambito del PNRR con autorizzazione a pubblicare i bandi e ad assumere il personale.<a href=\"https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/tavola-3.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-17009\" src=\"https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/tavola-3-1024x114.png\" alt=\"\" width=\"625\" height=\"70\" srcset=\"https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/tavola-3-1024x114.png 1024w, https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/tavola-3-300x33.png 300w, https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/tavola-3-768x85.png 768w, https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/tavola-3-624x69.png 624w, https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/tavola-3.png 1315w\" sizes=\"auto, (max-width: 625px) 100vw, 625px\" \/><\/a>Entro <strong>giugno 2022<\/strong> avvio della procedura di assunzione di almeno <strong>168 dipendenti<\/strong> per l\u2019ufficio per il processo e i tribunali amministrativi ed entrata in servizio di tali dipendenti, il valore di riferimento deve essere il numero di membri del personale in servizio al <strong>31 dicembre 2021<\/strong>.<\/p>\n<p><strong>Entro giugno 2024<\/strong><\/p>\n<ul>\n<li>\u00c8 prevista la conclusione delle procedure di assunzione per i tribunali amministrativi di almeno <strong>326 dipendenti<\/strong> per l\u2019ufficio per il processo e per i tribunali amministrativi ed entrata in servizio di tali dipendenti, il valore di riferimento deve essere il numero di dipendenti del personale nel secondo trimestre del 2022.<\/li>\n<\/ul>\n<p><a href=\"https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/raccordo-326-PNRR-giustizia.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-17041\" src=\"https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/raccordo-326-PNRR-giustizia-1024x120.png\" alt=\"\" width=\"625\" height=\"73\" srcset=\"https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/raccordo-326-PNRR-giustizia-1024x120.png 1024w, https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/raccordo-326-PNRR-giustizia-300x35.png 300w, https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/raccordo-326-PNRR-giustizia-768x90.png 768w, https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/raccordo-326-PNRR-giustizia-624x73.png 624w, https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/raccordo-326-PNRR-giustizia.png 1308w\" sizes=\"auto, (max-width: 625px) 100vw, 625px\" \/><\/a><\/p>\n<p><strong>PNRR &#8211; Gli investimenti previsti nella giustizia amministrativa<em><br \/><\/em><\/strong><\/p>\n<p>Per la Giustizia Amministrativa (Primo grado \u2013 TAR &#8211; Grado di appello presso Consiglio di Stato) \u00e8 previsto un rafforzamento per l&#8217;Ufficio per il processo e i tribunali amministrativi. La conclusione delle procedure \u00e8 prevista con l\u2019assunzione e l\u2019entrata in servizio per i tribunali amministrativi di almeno <strong>326 dipendenti.<\/strong><\/p>\n<p>Ricordo che la giustizia amministrativa si occupa di ricorsi di <span dir=\"ltr\" role=\"presentation\">Edilizia <\/span><span dir=\"ltr\" role=\"presentation\">e urba<\/span><span dir=\"ltr\" role=\"presentation\">nistica, Autorizzazioni e concessioni, Pubblico impiego, sicurezza, Appalti pubblici, lavori e <br role=\"presentation\" \/>forniture, ambiente, servizio sanitario nazionale, ricorsi presentati da persone di cittadinanza straniera in tema di: permesso di soggiorno; istanza di emersione da rapporto di lavoro irregolare; risarcimento del danno.<\/span><\/p>\n<p>Con la recente norma (<strong><span style=\"color: #ff0000;\"><a style=\"color: #ff0000;\" href=\"https:\/\/www.normattiva.it\/uri-res\/N2Ls?urn:nir:stato:legge:2021-08-06;113\">L.n.113\/2021<\/a><\/span>)<\/strong> si modifica il codice del processo amministrativo e si rafforza la capacit\u00e0 amministrativa delle pubbliche amministrazioni funzionale all&#8217;attuazione del Piano nazionale di ripresa e resilienza (PNRR), per l&#8217;efficienza della giustizia amministrativa, si introduce una particolare disciplina per i ricorsi \u201cdi immediata definizione\u201d per i quali si prevede, anche su input dell\u2019Ufficio del processo, la trattazione alla prima Camera di Consiglio utile ed in tempi quindi molto ristretti. La stessa sentenza dovr\u00e0 essere redatta in forma semplificata.<\/p>\n<p>Secondo il cronoprogramma del PNRR per il 2022 \u00e8 necessario avviare le procedure per l&#8217;assunzione di almeno <strong>168 dipendenti<\/strong> per l&#8217;Ufficio per il processo e i tribunali amministrativi con l&#8217;entrata in servizio di tali dipendenti.<\/p>\n<p>Tale intervento intende attuare la:<\/p>\n<ul>\n<li>riduzione dell\u2019arretrato giudiziario del Consiglio di Stato con la riduzione del 35% idel numero di cause pendenti, il dato di partenza \u00e8 i<strong>l 2019 (24.010 procedimenti)<\/strong> presso il consiglio di Stato (secondo grado);<a href=\"https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/raccordo-6-PNRR-giustizia.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-17017\" src=\"https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/raccordo-6-PNRR-giustizia-1024x78.png\" alt=\"\" width=\"625\" height=\"48\" srcset=\"https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/raccordo-6-PNRR-giustizia-1024x78.png 1024w, https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/raccordo-6-PNRR-giustizia-300x23.png 300w, https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/raccordo-6-PNRR-giustizia-768x58.png 768w, https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/raccordo-6-PNRR-giustizia-624x47.png 624w, https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/raccordo-6-PNRR-giustizia.png 1315w\" sizes=\"auto, (max-width: 625px) 100vw, 625px\" \/><\/a><\/li>\n<li>riduzione dell\u2019arretrato giudiziario dei tribunali amministrativi regionali con la riduzione del 25% del <strong>numero di cause pendenti,<\/strong> il dato di partenza \u00e8 i<strong>l 2019 (109.029 procedimenti),<\/strong> dinanzi ai tribunali amministrativi regionali (tribunali amministrativi di primo grado)<a href=\"https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/raccordo-5-PNRR-giustizia.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-17016\" src=\"https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/raccordo-5-PNRR-giustizia-1024x94.png\" alt=\"\" width=\"625\" height=\"57\" srcset=\"https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/raccordo-5-PNRR-giustizia-1024x94.png 1024w, https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/raccordo-5-PNRR-giustizia-300x28.png 300w, https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/raccordo-5-PNRR-giustizia-768x71.png 768w, https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/raccordo-5-PNRR-giustizia-624x57.png 624w, https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/raccordo-5-PNRR-giustizia.png 1315w\" sizes=\"auto, (max-width: 625px) 100vw, 625px\" \/><\/a>\n<p>\u00a0<\/p>\n<\/li>\n<\/ul>\n<p><strong>Entro giugno 2026<\/strong><\/p>\n<ul>\n<li style=\"list-style-type: none;\">\n<ul>\n<li>Riduzione dell\u2019arretrato giudiziario dei tribunali amministrativi regionali (primo grado).<\/li>\n<li>Riduzione del 70% del numero di cause pendenti <strong>(109.029) nel 2019<\/strong> dinanzi ai tribunali amministrativi regionali (tribunali amministrativi di primo grado).<\/li>\n<li>Sottolineo che le cause pendenti ai tribunali amministrativi di primo grado <strong><a href=\"https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/giustizia-istat-annuario-6.png\"><span style=\"color: #ff0000;\">secondo l&#8217;Istat sono invece <\/span><\/a><a href=\"https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/giustizia-istat-annuario-6.png\"><span style=\"color: #ff0000;\"><span dir=\"ltr\" role=\"presentation\">149.958<\/span> nel 2019<\/span><\/a><\/strong> e non 109 mila cme riportato nel piano, quindi la riduzione del 70% andrebbe calcolata sul dato certificato dall&#8217;ente pubblico.<a href=\"https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/raccordo-7-PNRR-giustizia.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-17018\" src=\"https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/raccordo-7-PNRR-giustizia-1024x115.png\" alt=\"\" width=\"625\" height=\"70\" srcset=\"https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/raccordo-7-PNRR-giustizia-1024x115.png 1024w, https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/raccordo-7-PNRR-giustizia-300x34.png 300w, https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/raccordo-7-PNRR-giustizia-768x86.png 768w, https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/raccordo-7-PNRR-giustizia-624x70.png 624w, https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/raccordo-7-PNRR-giustizia.png 1315w\" sizes=\"auto, (max-width: 625px) 100vw, 625px\" \/><\/a><\/li>\n<li>riduzione del 70% del numero di cause pendenti <strong>(24.010) nel 2019<\/strong> presso il consiglio di Stato (secondo grado).<a href=\"https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/raccordo-8-PNRR-giustizia.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-17020\" src=\"https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/raccordo-8-PNRR-giustizia-1024x78.png\" alt=\"\" width=\"625\" height=\"48\" srcset=\"https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/raccordo-8-PNRR-giustizia-1024x78.png 1024w, https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/raccordo-8-PNRR-giustizia-300x23.png 300w, https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/raccordo-8-PNRR-giustizia-768x58.png 768w, https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/raccordo-8-PNRR-giustizia-624x47.png 624w, https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/raccordo-8-PNRR-giustizia.png 1315w\" sizes=\"auto, (max-width: 625px) 100vw, 625px\" \/><\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p><strong>PNRR &#8211; <\/strong><strong>Efficientamento degli edifici giudiziari<\/strong><\/p>\n<p>Con il REGIO DECRETO 30 gennaio 1941, n. 12 Ordinamento giudiziario \u201c<em>il numero, le sedi, le circoscrizioni territoriali degli uffici giudiziari \u2026.ed il ruolo organico della magistratura sono determinati dalle tabelle poste nel decreto .., fatta eccezione per i giudici conciliatori<\/em>\u201d. Logico che le tabelle sono aggiornate a cura del ministero.<\/p>\n<p>In ambito giudiziario <span style=\"color: #ff0000;\"><a style=\"color: #ff0000;\" href=\"https:\/\/www.istat.it\/it\/files\/2013\/12\/Cap_6.pdf\"><strong><span style=\"color: #ff0000;\">all\u2019inizio dell\u2019anno 2012<\/span><\/strong><\/a><\/span> risultavano i seguenti uffici giudiziari:<\/p>\n<ul>\n<li><span style=\"color: #ff0000;\"><a style=\"color: #ff0000;\" href=\"https:\/\/www.cortedicassazione.it\/corte-di-cassazione\/\"><strong><span style=\"color: #ff0000;\">Corte Suprema <\/span><span style=\"color: #ff0000;\">di cassazione<\/span><\/strong><\/a><\/span><\/li>\n<li>29 <strong><span style=\"color: #ff0000;\"><a style=\"color: #ff0000;\" href=\"http:\/\/www.integrationarci.it\/wp-content\/uploads\/2015\/12\/Lista-corti-di-appello-in-Italia-con-relativa-competenza-asilo-e-accoglienza-Paolo-Sandroni-Copia.pdf\">Corti di appello<\/a><\/span><\/strong> (di cui 3 sezioni distaccate), la corte di appello ha sede nel capoluogo dei distretti indicati nella tabella A dell\u2019ordinamento giudiziario ed esercita la giurisdizione nelle cause di appello delle sentenze pronunciate in primo grado dai tribunali in materia civile e penale.<\/li>\n<li>29 Corti di assise di appello (di cui 3 sezioni distaccate)<\/li>\n<li>93 Corti di assise<\/li>\n<li>166 Tribunali ordinari (il tribunale ordinario ha sede in ogni capoluogo determinato nella tabella A dell\u2019ordinamento giudiziario. Il tribunale ordinario: a) esercita la giurisdizione in primo grado e in appello, contro le sentenze pronunciate dal giudice di pace, in materia civile; b) esercita la giurisdizione in primo grado in materia penale; c) esercita le funzioni di giudice tutelare; d) esercita nei modi stabiliti dalla legge le altre funzioni ad esso deferite).<\/li>\n<li>220 Sezioni distaccate di tribunale<\/li>\n<li>29 Tribunali per i minorenni<\/li>\n<li>29 Tribunali di sorveglianza<\/li>\n<li>Tribunale superiore delle acque pubbliche<\/li>\n<li>8 Tribunali regionali delle acque pubbliche (Sedi di Tribunali Regionali delle Acque Pubbliche 1\u00b0 &#8211; Cagliari 2\u00b0 &#8211; Firenze\u00a0\u00a0\u00a0\u00a0\u00a0 3\u00b0 &#8211; Milano\u00a0\u00a0 4\u00b0 &#8211; Napoli\u00a0\u00a0\u00a0\u00a0 5\u00b0 &#8211; Palermo 6\u00b0 &#8211; Roma 7\u00b0 &#8211; Torino 8\u00b0 &#8211; Venezia)<\/li>\n<li>58 Uffici di sorveglianza<\/li>\n<li>846 Giudici di pace (dal 2012 con la giustizia di prossimit\u00e0 le sedi degli uffici del giudice di pace sono mantenute con oneri a carico degli enti locali)<\/li>\n<li>385 Uffici notificazioni esecuzioni e protesti<\/li>\n<li>14 Commissariati agli usi civici<\/li>\n<li>166 Procure della Repubblica presso i tribunali<\/li>\n<li>29 Procure della Repubblica presso i tribunali per i minorenni<\/li>\n<li>29 Procure generali della Repubblica presso le corti d\u2019appello<\/li>\n<li>Procura generale della Repubblica presso la corte suprema di cassazione<\/li>\n<li><a href=\"https:\/\/www.giustizia.it\/giustizia\/it\/contentview.page?contentId=ART979440&amp;previsiousPage=mg_1_29_14_1\"><strong><span style=\"color: #ff0000;\">107 uffici centrali archivi notarili<\/span><\/strong><\/a><\/li>\n<\/ul>\n<p>Per quanto riguarda la giustizia amministrativa e contabile sono presenti <br \/>sul territorio nazionale i seguenti uffici:<\/p>\n<ul>\n<li>\u00a0Tribunali amministrativi regionali (21 tribunali e 8 sezioni)<\/li>\n<li>Consiglio di Stato (3 sezioni)<\/li>\n<li>Consiglio di giustizia amministrativa per la regione siciliana (1 sezione)<\/li>\n<li>Corte dei conti (20 sezioni giurisdizionali regionali).<\/li>\n<\/ul>\n<p>Nell\u2019ambito delle strutture penitenziarie per adulti si annoverano:<\/p>\n<ul>\n<li><strong><a href=\"https:\/\/www.giustizia.it\/cmsresources\/cms\/documents\/dap_patrimonio_immobiliare_2020.pdf\"><span style=\"color: #ff0000;\">213 istituti penitenziari<\/span><\/a><\/strong> di cui: 209 Case circondariali e\/o di reclusione, di cui: 1 Istituto di custodia attenuata per madri, 2 Istituti di custodia per tossicodipendenti, 1 Centro penitenziario.<br \/><br \/><\/li>\n<li>1 casa di cura e custodia<\/li>\n<li>2 case di lavoro e colonie agricole<\/li>\n<li>5 ospedali psichiatrici giudiziari<\/li>\n<li>16 provveditorati regionali<\/li>\n<\/ul>\n<p>Le strutture minorili comprendono invece:<\/p>\n<ul>\n<li>27 Centri di prima accoglienza<\/li>\n<li><strong><a href=\"https:\/\/www.giustizia.it\/cmsresources\/cms\/documents\/dgmc_patrimonio_immobiliare_2020.pdf\"><span style=\"color: #ff0000;\">12 Centri per la giustizia minorile<\/span><\/a><\/strong><\/li>\n<li>12 Comunit\u00e0 per minori (non sono conteggiate le comunit\u00e0 private)<\/li>\n<li>19 Istituti penali per i minorenni<\/li>\n<li>1 Scuola di formazione del personale per i minorenni<\/li>\n<li>58 Uffici di servizio sociale per minorenni<\/li>\n<\/ul>\n<p>Dal 2012 con la legge 14 settembre 2011, n. 148, sono state adottate misure urgenti per la stabilizzazione finanziaria e per lo sviluppo. Delega al Governo per la riorganizzazione della distribuzione sul territorio degli uffici giudiziari, ma da allora ad oggi cosa si \u00e8 fatto?<\/p>\n<p>Nell\u2019anno 2012 \u00e8 iniziato un processo di riordino della geografia giudiziaria che ha comportato, tra le misure, una riduzione nel numero di alcuni tipi di Ufficio. Lo scandalo rappresentato dai dati sulla lentezza della giustizia ha portato anche ad alcune riforme, come<strong> l\u2019accorpamento dei tribunali.<\/strong> Queste azioni sono state necessarie per godere di economie di scala, ritenute assolutamente necessarie alla creazione di \u201ctribunali per le imprese\u201d, per velocizzare le dispute riguardanti le aziende. \u201c<em>L\u2019intervento normativo ha riguardato la riorganizzazione degli uffici di primo grado \u201cordinari<\/em>\u201d esistenti (165 tribunali, con relative procure, 220 sezioni distaccate di tribunale e 667 uffici del giudice di Pace), c\u2019\u00e8 stato anche bisogno di un rafforzamento dell\u2019organico, con personale per esempio proveniente dalle Province (leggi anche il decreto legislativo 7 settembre 2012, n. 155 concernente la &#8220;Nuova organizzazione dei tribunali ordinari e degli uffici del pubblico ministero).<\/p>\n<p><span style=\"color: #ff0000;\"><strong><a style=\"color: #ff0000;\" href=\"https:\/\/giustizia.usb.it\/fileadmin\/archivio\/giustizia\/volantini_documenti\/Testo_integrale_commissione_Vietti_sul_riordino_della_geografia_giudiziaria.pdf\">&#8220;Nel 2014 la delega<\/a><\/strong><\/span> conferita al governo riguardava i soli uffici di primo grado ed era caratterizzata da due fondamentali limiti particolarmente condizionanti l\u2019intervento di razionalizzazione proposto: <br \/>1. Il vincolo del mantenimento dei tribunali ordinari (con relativa procura) aventi sede nei circondari di comuni capoluogo di provincia alla data del 30 giugno 2011; <br \/>2. L\u2019obbligo di \u201c<em>garantire che, all&#8217;esito degli interventi di riorganizzazione, ciascun distretto di corte d&#8217;appello, incluse le sue sezioni distaccate, comprenda non meno di tre degli attuali tribunali con relative procure della Repubblica<\/em>\u201d (art. 1 lettera f) della delega, nota come \u201c<strong>regola del tre<\/strong>\u201d).<\/p>\n<p>Nella commissione Vietti del 2016 emerge la necessit\u00e0 di legare l&#8217;assetto territoriale degli uffici giudiziari a criteri oggettivi e omogenei che tengano conto:<\/p>\n<ul>\n<li><strong>dell&#8217;estensione del territorio<\/strong><\/li>\n<li><strong>del numero degli abitanti<\/strong><\/li>\n<li><strong>dei carichi di lavoro e dell&#8217;indice delle sopravvenienze<\/strong><\/li>\n<li><strong>della specificit\u00e0 territoriale del bacino di utenza<\/strong> anche con riguardo alla <u>situazione infrastrutturale<\/u> e del <span style=\"text-decoration: underline;\">tasso d&#8217;impatto della <strong>criminalit\u00e0 organizzata<\/strong><\/span>, nonch\u00e9 della necessit\u00e0 di razionalizzare il servizio giustizia nelle grandi aree metropolitane\u201d (leggi il <a href=\"https:\/\/giustizia.usb.it\/fileadmin\/archivio\/giustizia\/volantini_documenti\/Testo_integrale_commissione_Vietti_sul_riordino_della_geografia_giudiziaria.pdf\"><strong><span style=\"color: #ff0000;\">testo<\/span><\/strong><\/a><strong>)<\/strong>. <span style=\"text-decoration: underline;\">Sulla base di questi criteri oggettivi bisognerebbe d<span dir=\"ltr\" role=\"presentation\">efinire e costruire i livelli essenziali delle prestazioni giudiziarie (LEPG).<\/span><\/span><\/li>\n<\/ul>\n<p>Per incrementare la disponibilit\u00e0 di uffici l\u2019amministrazione della Giustizia si \u00e8 avvalsa dell\u2019opportunit\u00e0 del Piano Nazionale di Ripresa e Resilienza (<strong>PNRR<\/strong>) attraverso la componente per l\u2019efficienza energetica e riqualificazione degli edifici che ha previsto un investimento di appena <strong>411,7 milioni di euro<\/strong> teso ad efficientare gli edifici giudiziari (<strong>1.2 efficientamento degli edifici giudiziari<\/strong>) con l\u2019obiettivo di ristrutturarli con materiali sostenibili e misure antisismiche.<\/p>\n<p><a href=\"https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/raccordo-9-PNRR-giustizia.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-17022\" src=\"https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/raccordo-9-PNRR-giustizia-1024x350.png\" alt=\"\" width=\"625\" height=\"214\" srcset=\"https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/raccordo-9-PNRR-giustizia-1024x350.png 1024w, https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/raccordo-9-PNRR-giustizia-300x102.png 300w, https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/raccordo-9-PNRR-giustizia-768x262.png 768w, https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/raccordo-9-PNRR-giustizia-624x213.png 624w, https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/raccordo-9-PNRR-giustizia.png 1315w\" sizes=\"auto, (max-width: 625px) 100vw, 625px\" \/><\/a>In particolare con l<strong>\u2019investimento 1.2 del PNRR <\/strong>per la costruzione di edifici, riqualificazione e rafforzamento dei beni immobili dell&#8217;amministrazione della giustizia si mira a ristrutturare e riqualificare le strutture inadeguate.<\/p>\n<p>Oltre all&#8217;importante ruolo dato all&#8217;efficientamento dei consumi energetici, il programma mira inoltre a garantire la sostenibilit\u00e0 economica, ambientale e sociale degli interventi attraverso l&#8217;uso di materiali sostenibili e l&#8217;utilizzo di <strong>energia elettrica autoprodotta da fonti rinnovabili<\/strong>. Gli interventi devono inoltre adattare le strutture per ridurre la vulnerabilit\u00e0 sismica degli edifici.<\/p>\n<p>L&#8217;investimento si focalizza sulla manutenzione di beni esistenti, consentendo la tutela, la valorizzazione e il restauro del patrimonio storico che spesso caratterizza gli uffici dell&#8217;amministrazione della giustizia italiana.<\/p>\n<p>Il cronoprogramma degli interventi prevede di agire <strong>entro la met\u00e0 del 2026<\/strong> su <strong>290.000 mq di uffici<\/strong>, <strong>tribunali e cittadelle giudiziarie, efficientando 48 strutture,<\/strong> migliorando tecnologicamente l&#8217;erogazione dei servizi. Si specifica che l&#8217;intervento non deve comprendere le caldaie a gas naturale.<\/p>\n<p>L&#8217;elenco<strong> <u>indicativo riportato nel piano<\/u> PNRR <\/strong>dei comuni \u00e8 il seguente: Bari, Bergamo, Bologna, Cagliari, Firenze, Genova, Latina, Messina, Milano, Monza, Napoli, Palermo, Perugia, Reggio Calabria, Roma, Trani, Torino, Velletri e Venezia.<\/p>\n<p>Si ricorda che gli immobili sedi degli uffici giudiziari dislocati sul territorio italiano (non ricompresi <span style=\"color: #ff0000;\"><a style=\"color: #ff0000;\" href=\"https:\/\/dati.agenziademanio.it\/#\/opendata\"><strong><span style=\"color: #ff0000;\">fra quelli demaniali<\/span><\/strong><\/a>),<\/span> in base ad una vecchia <span style=\"color: #ff0000;\"><strong><a style=\"color: #ff0000;\" href=\"https:\/\/www.normattiva.it\/uri-res\/N2Ls?urn:nir:stato:legge:1941-04-24;392\">legge n. 392 del 1941<\/a><\/strong><\/span> &#8211; Trasferimento ai Comuni del servizio dei locali e dei mobili degli Uffici giudiziari, sono solo in uso degli uffici giudiziari, ma restano di propriet\u00e0 dei Comuni di riferimento.<\/p>\n<p>La ricognizione delle informazioni identificative di tali immobili \u00e8 possibile, pertanto, consultando le pubblicazioni delle amministrazioni comunali. Se ne deduce che gli interventi previsti con l<strong>\u2019investimento 1.2 del PNRR<\/strong> non si potranno monitorare centralmente (presso il ministero della giustizia o MEF) ma si dovranno inseguire le gare di appalto espletate in ciascun comune citato. Un monitoraggio di questo tipo sembra oltre che dispendioso e complesso anche poco efficace perch\u00e9 l&#8217;Indicatore qualitativo (traguardi)\u00a0 previsto nel PNRR che riguarda le notifiche dell&#8217;aggiudicazione di tutti i contratti pubblici a seguito di una procedura di appalto pubblico non pu\u00f2 dare informazioni sul completamento delle opere previste ed effettivamente realizzate (si pensi al tipo di certificazione che permette di garantire la sostenibilit\u00e0 economica, ambientale e sociale con l&#8217;uso di materiali sostenibili e la verifica della conformit\u00e0 con i criteri di sostenibilit\u00e0 per l&#8217;utilizzo di <strong>energia elettrica autoprodotta da fonti rinnovabili)<\/strong>.\u00a0Il PNRR prevede di utilizzare quale indicatore qualitativo le &#8220;notifiche dell&#8217;aggiudicazione di gara&#8221; dato molto generico per monitorare il risultato atteso (output) previsto dell\u2019investimento ovvero:<\/p>\n<ul>\n<li>la riduzione della vulnerabilit\u00e0 sismica di 48 edifici giudiziari e loro efficientamento energetico;<\/li>\n<li>la manutenzione, tutela, valorizzazione e recupero di un vasto patrimonio storico;<\/li>\n<li>il miglioramento delle strutture inadeguate che influiscono negativamente sull\u2019amministrazione della giustizia;<\/li>\n<li>la maggiore efficienza, resilienza ed erogazione tecnologica dei servizi giudiziari.<\/li>\n<\/ul>\n<p>Bisognerebbe implementare invece un monitoraggio costante per minimizzare i consumi e l\u2019impatto ambientale dei 48 edifici riqualificati: come ad esempio utilizzare il risparmio in tonnellate di CO2 e di Ktep all\u2019anno, con conseguente riduzione delle emissioni di CO2.<br \/><br \/><\/p>\n<p><strong>PNRR &#8211;\u00a0 Traguardo Digitalizzazione del sistema giudiziario<\/strong><em><br \/><\/em><\/p>\n<p><a href=\"https:\/\/www.mise.gov.it\/images\/stories\/documenti\/ITALIA_Strategia_BUL-Piano_di_investimenti_fin.pdf\"><strong><span style=\"color: #ff0000;\">Con la Strategia Italiana per la Banda Ultra larga<\/span><\/strong><\/a>, si intende recuperare il gap infrastrutturale del nostro Paese rispetto agli ambiziosi obiettivi <strong><span style=\"color: #ff0000;\"><a style=\"color: #ff0000;\" href=\"https:\/\/www.europarl.europa.eu\/factsheets\/it\/sheet\/64\/un-agenda-digitale-europea\">dell\u2019Agenda Digitale Europea<\/a><\/span><\/strong>. Riguardo la digitalizzazione del sistema giudiziario \u00e8 fondamentale quindi che oltre a prevedere l&#8217;<strong>efficientamento degli edifici giudiziari\u00a0<\/strong> in termini sostenibili e misure antisismiche sia garantito anche alle strutture degli edifici della giustizia l&#8217;accesso alla banda ultralarga per garantire la gestione efficiente della mole di dati che il sistema giudiziario dovr\u00e0 trattare come:<\/p>\n<ol>\n<li>il Processo Civile Telematico con la definitiva telematizzazione di Giudice di Pace ed UNEP;<\/li>\n<li>il potenziamento del Registro Penale Informatizzato (integrazione ed interoperabilit\u00e0) con massima condivisione dei dati tra i soggetti coinvolti.<\/li>\n<li>la digitalizzazione degli atti, gestione documentale, gestione delle notifiche (legge di stabilit\u00e0 2016, n. 208\/2015<a href=\"#_ftnref4\">[5] <\/a>etc.<\/li>\n<\/ol>\n<p>Con il PNRR <strong>Obiettivo M1C1-38 Riforma 1.8 \u2013<\/strong> la <strong><span style=\"color: #ff0000;\"><a style=\"color: #ff0000;\" href=\"https:\/\/www.agid.gov.it\/sites\/default\/files\/repository_files\/piano_triennale_per_linformatica_nella_pa_2020-2022.pdf\">digitalizzazione<\/a><\/span><\/strong> del sistema giudiziario \u00e8 visto come un fattore importante trasversale anche per la transizione digitale del sistema che impatter\u00e0 poi su tutti gli ambiti giudiziari.<\/p>\n<p>Sono stati stanziati <strong><span style=\"color: #ff0000;\">133 milioni di euro<\/span> (<\/strong>Traguardo &#8211; Digitalizzazione del sistema giudiziario)\u00a0 per la digitalizzazione del sistema giudiziario <strong>del Ministero della Giustizia<\/strong> con la scadenza prevista per il 2023 per raggiungere la gestione elettronica obbligatoria di tutti i documenti e il processo dovr\u00e0 essere interamente telematico nei procedimenti civili.\u00a0 <a href=\"https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/raccordo-10-PNRR-giustizia.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-17028\" src=\"https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/raccordo-10-PNRR-giustizia-1024x520.png\" alt=\"\" width=\"625\" height=\"317\" srcset=\"https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/raccordo-10-PNRR-giustizia-1024x520.png 1024w, https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/raccordo-10-PNRR-giustizia-300x152.png 300w, https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/raccordo-10-PNRR-giustizia-768x390.png 768w, https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/raccordo-10-PNRR-giustizia-624x317.png 624w, https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/raccordo-10-PNRR-giustizia.png 1315w\" sizes=\"auto, (max-width: 625px) 100vw, 625px\" \/><\/a> La riforma prevista \u00e8 la \u201c<strong>1.8 \u2013 Digitalizzazione del sistema giudiziario<\/strong>\u201d che prevede l&#8217;obbligatoriet\u00e0 del fascicolo telematico e il completamento del processo civile telematico. Punta anche alla digitalizzazione del processo penale di primo grado, esclusa l&#8217;udienza preliminare. Da ultimo intende introdurre una banca dati delle decisioni civili gratuita, pienamente accessibile e consultabile conformemente alla legislazione vigente.<\/p>\n<p>Con l&#8217;investimento<strong> 1.6.2 &#8211; Digitalizzazione del Ministero della Giustizia<\/strong> entro il 2023 (Obiettivo <strong>M1C1-130<\/strong>) presso il Consiglio di Stato\u00a0 la documentazione giudiziaria dovr\u00e0 essere disponibile per analisi nei data warehouse. Saranno digitalizzati <strong>3,5 milioni di fascicoli giudiziari\u00a0<\/strong> relativi agli ultimi dieci anni di processi civili di tribunali e corti d&#8217;appello e agli ultimi dieci anni di atti relativi a procedimenti di legittimit\u00e0 emessi dalla Corte di Cassazione.<\/p>\n<p>Con i sistemi di conoscenza del cosiddetto \u201clago di dati\u201d (data lake) della giustizia, entro il 2026 l&#8217;esecuzione del contratto prevede di realizzare sei nuovi sistemi di conoscenza dei data lake, un repository altamente strutturato all\u2019archiviazione, analisi e correlazione dei dati sul:<\/p>\n<ol>\n<li>Sistema di anonimizzazione delle sentenze civili e penali<\/li>\n<li>Sistema di gestione integrato<\/li>\n<li>Sistema di gestione e analisi dei processi civili<\/li>\n<li>Sistema di gestione e analisi dei processi penali<\/li>\n<li>Sistema di statistiche avanzate sui processi civili e penali<\/li>\n<li>Sistema automatizzato per l&#8217;identificazione del rapporto vittima-autore del reato.<\/li>\n<\/ol>\n<p>L&#8217;esecuzione di ogni appalto pubblico ha inizio con un atto amministrativo specifico del responsabile della procedura, denominato &#8220;avvio dell&#8217;esecuzione&#8221;, ma non pu\u00f2 certo rappresentare un riferimento valido questo indicatore per monitorare il raggiungimento dell\u2019obiettivo ambizioso del Piano.<\/p>\n<p>&#8211; Con l\u2019<strong>investimento 1.6.5<\/strong> &#8211; <strong>Obiettivo M1C1-14 digitalizzazione del Consiglio di Stato<\/strong> si intende digitalizzare <strong>3,5 milioni di fascicoli giudiziari<\/strong> relativi agli ultimi dieci anni di processi civili di tribunali e corti d&#8217;appello e agli ultimi dieci anni di atti relativi a procedimenti di legittimit\u00e0 emessi dalla Corte di Cassazione.<a href=\"https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/PNRR-consiglio-stato.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-17493\" src=\"https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/PNRR-consiglio-stato-1024x465.png\" alt=\"\" width=\"625\" height=\"284\" srcset=\"https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/PNRR-consiglio-stato-1024x465.png 1024w, https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/PNRR-consiglio-stato-300x136.png 300w, https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/PNRR-consiglio-stato-768x349.png 768w, https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/PNRR-consiglio-stato-1536x697.png 1536w, https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/PNRR-consiglio-stato-2048x930.png 2048w, https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/PNRR-consiglio-stato-624x283.png 624w\" sizes=\"auto, (max-width: 625px) 100vw, 625px\" \/><\/a>&#8211; Con<strong> l\u2019investimento 1.6.5 Obiettivo M1C1-16<\/strong> <strong>entro il 2024<\/strong> il numero di atti giudiziari relativi al sistema di giurisdizione amministrativa (quali sentenze, pareri e decreti) dovr\u00e0 essere pienamente disponibili <span style=\"text-decoration: underline;\">nel data warehouse<\/span>.<\/p>\n<p>Infine nell&#8217;ambito dell&#8217;<strong>Investimento 1.6.5 &#8211; Digitalizzazione del Consiglio di Stato<\/strong> con l&#8217;obiettivo <strong>M1C1-153<\/strong> \u00e8 prevista la digitalizzazione <strong>di dieci milioni di fascicoli giudiziari<\/strong> relativi agli ultimi dieci anni di processi civili di tribunali e corti d&#8217;appello e agli ultimi dieci anni di atti relativi a procedimenti di legittimit\u00e0 emessi dalla Corte di Cassazione. L&#8217;Istat ha certificato soltanto nel 2020 <strong><span style=\"color: #ff0000;\"><a style=\"color: #ff0000;\" href=\"https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/giustizia-istat-annuario-6.png\">presso il Consiglio di Stato<\/a> <a style=\"color: #ff0000;\" href=\"https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/giustizia-istat-annuario-6.png\">22 mila ricorsi\u00a0 pendenti in appello a fine anno<\/a><\/span><\/strong>.<\/p>\n<p><strong>CONCLUSIONI <br \/><\/strong><\/p>\n<ul>\n<li>Nell&#8217;agenda 2030 si sottolinea la volont\u00e0 di <strong><span style=\"color: #ff0000;\"><a style=\"color: #ff0000;\" href=\"https:\/\/www.europarl.europa.eu\/about-parliament\/it\/democracy-and-human-rights\/fundamental-rights-in-the-eu\/ensuring-access-to-justice\">garantire un pari <\/a><a style=\"color: #ff0000;\" href=\"https:\/\/www.europarl.europa.eu\/about-parliament\/it\/democracy-and-human-rights\/fundamental-rights-in-the-eu\/ensuring-access-to-justice\">accesso alla giustizia <\/a><\/span>per tutti.<\/strong>\u00a0 Ma il PNRR non rafforza il diritto a un processo equo, si parla solo dell\u2019obiettivo finale di una riduzione dei tempi dei procedimenti entro i prossimi cinque anni, visto anche lo scarso numero attuale dei giudici, se non si risolvono prima i problemi strutturali del sistema giudiziario non si possono ottenere risultati effettivi.<\/li>\n<li>Un aspetto fondamentale \u00e8 il numero insufficiente di magistrati necessari per gestire la mole di procedimenti civili e penali pendenti, seppur i bandi di concorso sono partiti e il PNRR cerca di contribuire alla soluzione con l&#8217;assunzione di personale dipendente a tempo determinato (<strong>19.719 dipendenti<\/strong>) necessari nelle cancellerie, non si pu\u00f2 risolvere il problema atavico dei procedimenti pendenti a fine anno senza avere un numero sufficiente di giudici che ne determinano le sentenze definitive.<\/li>\n<li>Riguardo il patrimonio della giustizia nel PNRR si fa riferimento alla notifica come obiettivo raggiunto per monitorare il risultato atteso (output) dell\u2019investimento, considerando che saranno i comuni a gestire i fondi, bisognerebbe invece implementare un serio monitoraggio che misura l\u2019impatto ambientale effettivo dei 48 edifici riqualificati in termini di risparmio in tonnellate di CO2 e di Ktep all\u2019anno di tutto il patrimonio pubblico giudiziario e aggiungo che andrebbe fatto anche su tutto quello complessivo italiano.<\/li>\n<li>Bisognerebbe infine definire e costruire i <strong>livelli essenziali delle prestazioni giudiziarie LEPG<\/strong> e intervenire sulla geografia giudiziaria per razionalizzazione a livello territoriale la domanda e l&#8217;offerta di giustizia che tenga conto che ogni distretto per regione sia dotato di quei requisiti dimensionali minimi e coerenti con un modello di efficienza ideale individuato sulla base dell\u2019estensione territoriale, della popolazione amministrata, dell\u2019indice delle sopravvenienze e dei carichi di lavoro, tenendo in considerazione che gli uffici di primo grado erogano una serie di servizi direttamente collegati con il territorio amministrato, mentre il giudizio d\u2019appello ed i servizi erogati dalle Corti e dalle Procure Generali dovrebbero puntare sulla qualit\u00e0 e l\u2019efficienza del servizio erogato e che, anche per il giudice d\u2019appello, non pu\u00f2 prescindere il servizio da definire da requisiti dimensionali minimi in grado di garantire l\u2019equa distribuzione dei carichi nazionali e la specializzazione delle funzioni.<\/li>\n<li>Bisognerebbe inoltre definire e costruire <strong>i livelli essenziali delle prestazioni giudiziarie LEPG<\/strong> tenendo anche conto dei processi di ammodernamento in atto con la digitalizzazione dei servizi giudiziari che rende sempre meno rilevante la prossimit\u00e0 territoriale del giudice (sia per il cittadino sia per l\u2019utenza professionale) mentre emerge con evidenza la necessit\u00e0 di completare e migliorare la riforma della geografia giudiziaria ridisegnando anche i distretti di Corte di Appello come suggeriscono gli stessi magistrati in prima linea a gestire i procedimenti giudiziari.<\/li>\n<li>Il sistema giudiziario gestir\u00e0 attraverso il nuovo dipartimento per la transizione digitale: i nuovi servizi legati al Processo Civile Telematico, al Registro Penale Informatizzato (integrazione ed interoperabilit\u00e0) con massima condivisione dei dati tra i soggetti coinvolti, la digitalizzazione degli atti, la gestione documentale, la gestione delle notifiche; per efficientare questa mole di dati si possono mettere in comunicazione le strutture giudiziarie e utilizzare il <span style=\"color: #ff0000;\"><a style=\"color: #ff0000;\" href=\"https:\/\/www.gazzettaufficiale.it\/eli\/id\/2020\/09\/14\/20A04921\/sg\"><strong><span style=\"color: #ff0000;\">DL semplificazione<\/span><\/strong><\/a><\/span> e la piattaforma di interoperabilit\u00e0 digitale nazionale dati (POND) finalizzata proprio a favorire la conoscenza e l\u2019utilizzo del patrimonio informativo pubblico, con la condivisione dei dati si possono semplificare gli adempimenti amministrativi di cittadini e imprese.\u00a0<\/li>\n<li>La riforma della giustizia penale e civile italiana \u00e8 stata impostata tenendo conto della durata prognostica dei procedimenti caratterizzata da una grande variabilit\u00e0 tra le diverse sedi giudiziarie che avrebbero confermato una resa di giustizia molto differenziata all\u2019interno del nostro paese. In alcuni tribunali si riescono ad ottenere per\u00f2 delle performance che permetterebbero una radicale riduzione dei tempi della giustizia, si pu\u00f2 partire dallo studio di queste best practice per definire le prossime piante organiche e la conseguente assegnazione del personale.<\/li>\n<li><strong>Il punto 16.3 dell\u2019agenda 2030 &#8211; Promuovere lo stato di diritto a livello nazionale e internazionale e garantire un pari accesso alla giustizia per tutti<\/strong> si pu\u00f2 perseguire anche con un monitoraggio permanente attraverso un cruscotto di indicatori elaborati a partire dai LEPG, dalla piattaforma POND e integrando tutti i dati amministrativi disponibili nonch\u00e9 i dati contabili come quelli di costo per tipo di procedimento e le relative risorse umane allocate nei singoli uffici per permettere l&#8217;analisi tempestiva di indici come base per definire con criteri oggettivi l\u2019allocazione delle risorse (umane, finanziarie ed informatiche) complessive al sistema giudiziario.<\/li>\n<\/ul>\n<p><strong>QUESTIONI APERTE<\/strong><\/p>\n<ol>\n<li><strong>Leggi prima <span style=\"color: #ff0000;\"><a style=\"color: #ff0000;\" href=\"https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/prima-Interrogazione-riforma-giustizia-e-PNRR.pdf\">interrogazione<\/a><\/span><\/strong><\/li>\n<li><strong>Leggi seconda <span style=\"color: #ff0000;\"><a style=\"color: #ff0000;\" href=\"https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/seconda-Interrogazione-riforma-giustizia-e-PNRR-uff.pdf\">interrogazione<\/a><\/span><\/strong><\/li>\n<li><strong>Leggi terza <a href=\"https:\/\/www.monicamontella.it\/wordpress\/wp-content\/uploads\/2021\/12\/terza-Interrogazione-riforma-giustizia-e-PNRR-uff.pdf\"><strong><span style=\"color: #ff0000;\">interrogazione<\/span><\/strong><\/a><\/strong><\/li>\n<\/ol>\n<p>\u00a0<\/p>\n<p><strong>NOTE<br \/><\/strong><\/p>\n<p><a href=\"#_ftnref1\" name=\"_ftn1\">[1]<\/a> Misura il tempo medio che \u00e8 stato necessario per la definizione dei procedimenti conclusi nell\u2019anno di riferimento. La durata \u00e8 calcolata come differenza tra la data di iscrizione e la data in cui viene pubblicata la sentenza o il provvedimento di definizione.<\/p>\n<p><a href=\"#_ftnref2\" name=\"_ftn2\">[2]<\/a> Il registro SICID comprende quattro ruoli o macromaterie: affari contenziosi, controversie in materia di lavoro e previdenza, procedimenti speciali e sommari e volontaria giurisdizione; dal calcolo della durata sono esclusi l\u2019attivit\u00e0 del Giudice Tutelare, gli accertamenti tecnici preventivi in materia previdenziale e le verbalizzazioni di dichiarazioni giurate in Tribunale.<\/p>\n<p><a href=\"#_ftnref3\" name=\"_ftn3\">[3]<\/a> Misura il tempo medio che \u00e8 stato necessario per la definizione dei procedimenti conclusi nell\u2019anno di riferimento. La durata \u00e8 calcolata come differenza tra la data di iscrizione e la data di definizione<\/p>\n<p><a href=\"#_ftnref4\" name=\"_ftn4\">[4]<\/a> Il registro SIECIC comprende tre ruoli o macro materie: esecuzioni mobiliari, esecuzioni immobiliari e procedure concorsuali (istanze di fallimento, fallimenti e altre procedure concorsuali).<\/p>\n<p><a href=\"#_ftnref4\" name=\"_ftn4\">[5]<\/a> L&#8217;Agenzia per l&#8217;Italia digitale (Agid) predispone il <span style=\"color: #ff0000;\"><strong><a style=\"color: #ff0000;\" href=\"https:\/\/www.agid.gov.it\/it\/agenzia\/piano-triennale\">Piano triennale per l&#8217;informatica<\/a> <\/strong><\/span>nella pubblica amministrazione che \u00e8 approvato dal Presidente del Consiglio dei ministri o dal Ministro delegato. Il Piano contiene, per ciascuna amministrazione o categoria di amministrazioni, l&#8217;elenco dei beni e servizi informatici e di connettivita&#8217; e dei relativi costi, suddivisi in spese da sostenere per innovazione e spese per la gestione corrente, individuando altres\u00ec i beni e servizi la cui acquisizione riveste particolare rilevanza strategica.<\/p>\n<p><strong>FONTE DATI<\/strong><\/p>\n<p><strong>RAGIONERIA GENERALE DELLO STATO<\/strong><\/p>\n<p><strong><a href=\"https:\/\/openbdap.mef.gov.it\/\"><span style=\"color: #ff0000;\">Open Bdap<\/span><\/a><\/strong><\/p>\n<p><strong>ISTAT<\/strong><\/p>\n<p><strong><span style=\"color: #ff0000;\"><a style=\"color: #ff0000;\" href=\"https:\/\/ebiblio.istat.it\/SebinaOpac\/resource\/annuario-statistico-italiano\/IST0010812?tabDoc=taboggd\">ANNUARIO ARCHIVIO<\/a><\/span><\/strong><\/p>\n<p><span style=\"color: #ff0000;\"><strong><a style=\"color: #ff0000;\" href=\"https:\/\/www.istat.it\/it\/files\/2013\/12\/Cap_6.pdf\">ANNUARIO STATISTICO 2013<\/a><\/strong><\/span><\/p>\n<p><strong><span style=\"color: #ff0000;\"><a style=\"color: #ff0000;\" href=\"https:\/\/www.istat.it\/it\/files\/\/2014\/11\/C06.pdf\">ANNUARIO STATISTICO 2014<\/a><\/span><\/strong><\/p>\n<p><strong><span style=\"color: #ff0000;\"><a style=\"color: #ff0000;\" href=\"https:\/\/www.istat.it\/it\/files\/\/2015\/12\/C06.pdf\">ANNUARIO STATISTICO 2015<\/a><\/span><\/strong><\/p>\n<p><strong><span style=\"color: #ff0000;\"><a style=\"color: #ff0000;\" href=\"https:\/\/www.istat.it\/it\/files\/\/2016\/12\/C06.pdf\">ANNUARIO STATISTICO 2016<\/a><\/span><\/strong><\/p>\n<p><strong><span style=\"color: #ff0000;\"><a style=\"color: #ff0000;\" href=\"https:\/\/www.istat.it\/it\/files\/\/2017\/12\/C06.pdf\">ANNUARIO STATISTICO 2017<\/a><\/span><\/strong><\/p>\n<p><strong><span style=\"color: #ff0000;\"><a style=\"color: #ff0000;\" href=\"https:\/\/www.istat.it\/it\/files\/\/2018\/12\/C06.pdf\">ANNUARIO STATISTICO 2018<\/a><\/span><\/strong><\/p>\n<p><strong><span style=\"color: #ff0000;\"><a style=\"color: #ff0000;\" href=\"https:\/\/www.istat.it\/it\/files\/\/2019\/12\/C06.pdf\">ANNUARIO STATISTICO 2019<\/a><\/span><\/strong><\/p>\n<p><strong><span style=\"color: #ff0000;\"><a style=\"color: #ff0000;\" href=\"https:\/\/www.istat.it\/it\/files\/\/2020\/12\/C06.pdf\">ANNUARIO STATISTICO 2020<\/a><\/span><\/strong><\/p>\n<p><strong><span style=\"color: #ff0000;\"><a style=\"color: #ff0000;\" href=\"https:\/\/www.istat.it\/storage\/ASI\/2021\/capitoli\/C06.pdf\">ANNUARIO STATISTICO 2021<\/a><\/span><\/strong><\/p>\n<p><strong>MINISTERO DELLA GIUSTIZIA<\/strong><\/p>\n<p><a href=\"https:\/\/www.giustizia.it\/giustizia\/it\/mg_2_9_13.page\"><strong><span style=\"color: #ff0000;\">MONITORAGGIO flussi<\/span><\/strong><\/a><\/p>\n<p><strong>CORTE DI CASSAZIONE<\/strong><\/p>\n<p><strong><span style=\"color: #ff0000;\">ANNUARIO STATISTICO<\/span> <span style=\"color: #ff0000;\"><a style=\"color: #ff0000;\" href=\"https:\/\/www.cortedicassazione.it\/cassazione-resources\/resources\/cms\/documents\/20210107_ANNUARIO-Civile2020.pdf\">CIVILE<\/a> &#8211; <a href=\"https:\/\/www.cortedicassazione.it\/cassazione-resources\/resources\/cms\/documents\/ANNUARIO_PENALE_2020.pdf\"><span style=\"color: #ff0000;\">PENALE<\/span><\/a><\/span><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 Leggi prima interrogazione Leggi seconda interrogazione Leggi terza interrogazione Leggi la risoluzione respinta Leggi la relazione su GIUSTIZIA e PNRR \u00a0\u201cLa giustizia \u00e8 amministrata in nome del popolo. I giudici sono soggetti soltanto alla legge\u201d (art.101), e \u201cla funzione giurisdizionale \u00e8 esercitata da magistrati ordinari istituiti e regolati dalle norme sull\u2019ordinamento giudiziario\u201d (art.102) \u201cle [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[684,329],"tags":[685,687,686],"class_list":["post-16980","post","type-post","status-publish","format-standard","hentry","category-pnrr","category-trasparenza","tag-pnrr","tag-processo-telematico","tag-riforma-giustizia"],"_links":{"self":[{"href":"https:\/\/www.monicamontella.it\/wordpress\/wp-json\/wp\/v2\/posts\/16980","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.monicamontella.it\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.monicamontella.it\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.monicamontella.it\/wordpress\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.monicamontella.it\/wordpress\/wp-json\/wp\/v2\/comments?post=16980"}],"version-history":[{"count":661,"href":"https:\/\/www.monicamontella.it\/wordpress\/wp-json\/wp\/v2\/posts\/16980\/revisions"}],"predecessor-version":[{"id":17998,"href":"https:\/\/www.monicamontella.it\/wordpress\/wp-json\/wp\/v2\/posts\/16980\/revisions\/17998"}],"wp:attachment":[{"href":"https:\/\/www.monicamontella.it\/wordpress\/wp-json\/wp\/v2\/media?parent=16980"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.monicamontella.it\/wordpress\/wp-json\/wp\/v2\/categories?post=16980"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.monicamontella.it\/wordpress\/wp-json\/wp\/v2\/tags?post=16980"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}